{"id":9095,"date":"2022-05-30T11:06:17","date_gmt":"2022-05-30T04:06:17","guid":{"rendered":"http:\/\/54.169.157.213\/sci2pub\/?p=9095"},"modified":"2022-05-30T11:06:17","modified_gmt":"2022-05-30T04:06:17","slug":"safety-research-laboratory","status":"publish","type":"post","link":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/","title":{"rendered":"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21"},"content":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e19\u0e33\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e21\u0e2d\u0e01.2677-2558 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e47\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 ESPReL Checklist \u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 &#8220;ESPReL&#8221; (Enhancement of Safety Practice of Research Laboratory in Thailand) \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e27\u0e0a.)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e42\u0e14\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (Center for Occupational Safety Health and Workplace Environment Management; COSHEM)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e42\u0e14\u0e22 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e01\u0e23 \u0e08\u0e32\u0e21\u0e23\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e04\u0e37\u0e2d \u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33 &#8220;Peer Evaluation&#8221; \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e23\u0e48\u0e27\u0e21<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 Peer Evaluation \u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 Peer Evaluation \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 137 \u0e02\u0e49\u0e2d \u0e43\u0e19 7 \u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1.\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 2.\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 3.\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 4.\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d 5.\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e20\u0e31\u0e22\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 6.\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30 7.\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e01\u0e23 \u0e08\u0e32\u0e21\u0e23\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e23\u0e2d\u0e07\u0e41\u0e0a\u0e21\u0e1b\u0e4c Peer Evaluation \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e35 2558 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e08\u0e23\u0e34\u0e07\u0e08\u0e31\u0e07<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22 \u0e27\u0e0a. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e23\u0e27\u0e21\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 80 \u0e04\u0e34\u0e14\u0e41\u0e22\u0e01\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 50 \u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 1 \u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e15\u0e47\u0e21 100% \u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 3 \u0e1b\u0e35<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e08\u0e30\u0e25\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e2b\u0e49\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e35 2560 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 MU Safety Day \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e35<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e1b\u0e10\u0e21\u0e1a\u0e17 &#8220;Safety begin with me&#8221; \u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32 \u0e43\u0e19\u0e1b\u0e35 2560 &#8220;A Day of Fire Safety&#8221; \u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e43\u0e08\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e17 \u0e43\u0e19\u0e1b\u0e35 2561 &#8220;Safety Day : Safety Culture&#8221; \u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e1b\u0e35 2562 &#8220;Safety we CARES \u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e43\u0e19\u0e1b\u0e35 2563 \u0e41\u0e25\u0e30 &#8220;Safety Forward&#8221; \u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 15,000 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e1b\u0e35 2564<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e21\u0e32\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 MU Safety Day \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 &#8220;Safety Future&#8221; \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e43\u0e19\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 &#8220;\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a&#8221; 122 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e32\u0e01 17 \u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e01\u0e13\u0e11\u0e4c ESPReL \u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 100% \u0e08\u0e33\u0e19\u0e27\u0e19 4 \u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e04\u0e13\u0e30\u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e42\u0e21\u0e40\u0e25\u0e01\u0e38\u0e25 \u0e41\u0e25\u0e30 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e35 2566<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 1 \u0e43\u0e19 7 \u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07 ESPReL \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 COSHEM \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e.\u0e23.\u0e1a.\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e1e.\u0e28.2562 (Personal Data Protection Act; PDPA) \u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2565 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e16\u0e36\u0e07\u0e19\u0e35\u0e49<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e0a\u0e31\u0e22\u0e40\u0e25\u0e34\u0e28 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e1e\u0e23\u0e0a\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 1 \u0e43\u0e19 4 \u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e01\u0e13\u0e11\u0e4c ESPReL \u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 100% \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e22\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 (MUIT)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e40\u0e04\u0e22\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e28\u0e34\u0e23\u0e34\u0e23\u0e32\u0e0a \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e28\u0e34\u0e23\u0e34\u0e23\u0e32\u0e0a\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e44\u0e14\u0e49\u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 PDPA \u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e43\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e04\u0e27\u0e23\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e38\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e04\u0e27\u0e23\u0e21\u0e35 template \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e17\u0e23\u0e32\u0e1a\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e2a\u0e21\u0e2d \u0e04\u0e37\u0e2d &#8220;\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25&#8221; \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 &#8220;\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25&#8221; \u0e42\u0e14\u0e22\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23&#8221; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e0a\u0e31\u0e22\u0e40\u0e25\u0e34\u0e28 \u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e1e\u0e23\u0e0a\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23. \u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2b\u0e0d\u0e34\u0e07\u0e27\u0e25\u0e32\u0e2a\u0e34\u0e19\u0e35 \u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e04\u0e33\u0e14\u0e27\u0e07 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 ESPReL \u0e43\u0e19\u0e1b\u0e35 2565 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07 \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07 3 \u0e1b\u0e35\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e23\u0e01 (Q1) \u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 70 \u0e41\u0e25\u0e30\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e42\u0e25\u0e01 Academic Research by Subject \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e02\u0e2d\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 58 \u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882775.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9097\" src=\"http:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882775.jpg\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882775.jpg 700w, https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882775-300x225.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e04\u0e13\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c (ABSL3) \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e08\u0e31\u0e22\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d&#8221;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e04\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07 One Health \u0e42\u0e14\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07 &#8220;\u0e44\u0e02\u0e49\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e01&#8221; \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32\u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07 COVID-19 \u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19&#8221;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;\u0e42\u0e14\u0e22 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c (ABSL3) \u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e2f \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e28\u0e32\u0e25\u0e32\u0e22\u0e32 \u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e13 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19&#8221; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23. \u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2b\u0e0d\u0e34\u0e07\u0e27\u0e25\u0e32\u0e2a\u0e34\u0e19\u0e35 \u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e04\u0e33\u0e14\u0e27\u0e07 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e25\u0e31\u0e17 \u0e28\u0e32\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e07\u0e04\u0e13\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 ESPReL \u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e42\u0e14\u0e22 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e09\u0e25\u0e32\u0e01\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e09\u0e1a\u0e31\u0e1a<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e22\u0e32 (\u0e2d\u0e22.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e (\u0e2a\u0e2a\u0e2a.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e39\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32 \u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 (\u0e21.\u0e2a.\u0e20.) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 &#8220;\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e&#8221; \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e42\u0e0b\u0e40\u0e14\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30 \u0e44\u0e02\u0e21\u0e31\u0e19<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;\u0e40\u0e23\u0e32\u0e40\u0e19\u0e49\u0e19 &#8220;\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19&#8221; \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e41\u0e01\u0e49\u0e44\u0e02&#8221; \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49 &#8220;\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19&#8221; \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 &#8220;Safety Culture&#8221; \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22&#8221;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e04\u0e19\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d&#8221; \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e0a\u0e25\u0e31\u0e17 \u0e28\u0e32\u0e19\u0e15\u0e34\u0e27\u0e23\u0e32\u0e07\u0e04\u0e13\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 www.mahidol.ac.th<\/p>\n<hr>\n<p><strong>\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e02\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22 <\/strong><br \/>\n<strong>\u0e10\u0e34\u0e15\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e14\u0e0a\u0e1e\u0e23\u0e2b\u0e21<\/strong><br \/>\n\u0e19\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c (\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23) \u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b<br \/>\n\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e42\u0e17\u0e23. 0-2849-6210<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[199],"tags":[2345,2344,2343],"class_list":["post-9095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sci-news","tag-esprel","tag-2344","tag-2343"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 - \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 - \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SarawitNSTDA\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-30T04:06:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sarawitnstda\" \/>\n<meta name=\"twitter:site\" content=\"@sarawitnstda\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/\"},\"author\":{\"name\":\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#\\\/schema\\\/person\\\/4a99aa969f89e0a96197e52732fb8a4e\"},\"headline\":\"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\",\"datePublished\":\"2022-05-30T04:06:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/S__103882776.jpg\",\"keywords\":[\"ESPReL\",\"\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\",\"\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\"],\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e27\u0e34\u0e17\u0e22\u0e4c\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/\",\"name\":\"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 - \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/S__103882776.jpg\",\"datePublished\":\"2022-05-30T04:06:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/S__103882776.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/S__103882776.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/safety-research-laboratory\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/\",\"name\":\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\",\"description\":\"\u0e22\u0e48\u0e2d\u0e22\u0e42\u0e25\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#organization\",\"name\":\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-sarawit-web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-sarawit-web.jpg\",\"width\":100,\"height\":100,\"caption\":\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SarawitNSTDA\",\"https:\\\/\\\/x.com\\\/sarawitnstda\",\"https:\\\/\\\/www.youtube.com\\\/@SARAWITTV\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/#\\\/schema\\\/person\\\/4a99aa969f89e0a96197e52732fb8a4e\",\"name\":\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69d7795a09ccb14ff54789f43fcaeae04d61343d9e1f3574295d71261486dccc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69d7795a09ccb14ff54789f43fcaeae04d61343d9e1f3574295d71261486dccc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/69d7795a09ccb14ff54789f43fcaeae04d61343d9e1f3574295d71261486dccc?s=96&d=mm&r=g\",\"caption\":\"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.\"},\"description\":\"\u0e22\u0e48\u0e2d\u0e22\u0e42\u0e25\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13 sarawit@nstda.or.th\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/sci2pub\\\/author\\\/paritat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 - \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 - \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","og_description":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; \u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/","og_site_name":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","article_publisher":"https:\/\/www.facebook.com\/SarawitNSTDA","article_published_time":"2022-05-30T04:06:17+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg","type":"image\/jpeg"}],"author":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","twitter_card":"summary_large_image","twitter_creator":"@sarawitnstda","twitter_site":"@sarawitnstda","twitter_misc":{"Written by":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#article","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/"},"author":{"name":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","@id":"https:\/\/www.nstda.or.th\/sci2pub\/#\/schema\/person\/4a99aa969f89e0a96197e52732fb8a4e"},"headline":"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21","datePublished":"2022-05-30T04:06:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/"},"wordCount":239,"publisher":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/#organization"},"image":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg","keywords":["ESPReL","\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22","\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23"],"articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e27\u0e34\u0e17\u0e22\u0e4c"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/","url":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/","name":"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 - \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg","datePublished":"2022-05-30T04:06:17+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#primaryimage","url":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg","contentUrl":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/sci2pub\/safety-research-laboratory\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nstda.or.th\/sci2pub\/"},{"@type":"ListItem","position":2,"name":"\u0e21.\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/sci2pub\/#website","url":"https:\/\/www.nstda.or.th\/sci2pub\/","name":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","description":"\u0e22\u0e48\u0e2d\u0e22\u0e42\u0e25\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13","publisher":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/sci2pub\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/sci2pub\/#organization","name":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","url":"https:\/\/www.nstda.or.th\/sci2pub\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.nstda.or.th\/sci2pub\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2023\/06\/logo-sarawit-web.jpg","contentUrl":"https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2023\/06\/logo-sarawit-web.jpg","width":100,"height":100,"caption":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a."},"image":{"@id":"https:\/\/www.nstda.or.th\/sci2pub\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SarawitNSTDA","https:\/\/x.com\/sarawitnstda","https:\/\/www.youtube.com\/@SARAWITTV"]},{"@type":"Person","@id":"https:\/\/www.nstda.or.th\/sci2pub\/#\/schema\/person\/4a99aa969f89e0a96197e52732fb8a4e","name":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/69d7795a09ccb14ff54789f43fcaeae04d61343d9e1f3574295d71261486dccc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69d7795a09ccb14ff54789f43fcaeae04d61343d9e1f3574295d71261486dccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69d7795a09ccb14ff54789f43fcaeae04d61343d9e1f3574295d71261486dccc?s=96&d=mm&r=g","caption":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a."},"description":"\u0e22\u0e48\u0e2d\u0e22\u0e42\u0e25\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13 sarawit@nstda.or.th","url":"https:\/\/www.nstda.or.th\/sci2pub\/author\/paritat\/"}]}},"featured_image_urls":{"full":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",800,533,false],"thumbnail":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776-150x150.jpg",150,150,true],"medium":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776-768x512.jpg",640,427,true],"large":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",640,426,false],"1536x1536":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",800,533,false],"2048x2048":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",800,533,false],"benqu-img-size1":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",100,67,false],"benqu-img-size2":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",305,203,false],"benqu-img-size3":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",371,247,false],"benqu-img-size4":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",800,533,false],"benqu-img-size5":["https:\/\/www.nstda.or.th\/sci2pub\/wp-content\/uploads\/2022\/05\/S__103882776.jpg",780,520,false]},"author_info":{"display_name":"\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a.","author_link":"https:\/\/www.nstda.or.th\/sci2pub\/author\/paritat\/"},"category_info":"<a href=\"https:\/\/www.nstda.or.th\/sci2pub\/category\/sci-news\/\" rel=\"category tag\">\u0e02\u0e48\u0e32\u0e27\u0e27\u0e34\u0e17\u0e22\u0e4c<\/a>","tag_info":"\u0e02\u0e48\u0e32\u0e27\u0e27\u0e34\u0e17\u0e22\u0e4c","comment_count":0,"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/posts\/9095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/comments?post=9095"}],"version-history":[{"count":1,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/posts\/9095\/revisions"}],"predecessor-version":[{"id":9098,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/posts\/9095\/revisions\/9098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/media\/9096"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/media?parent=9095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/categories?post=9095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/sci2pub\/wp-json\/wp\/v2\/tags?post=9095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}