{"id":58649,"date":"2022-01-12T12:23:30","date_gmt":"2022-01-12T05:23:30","guid":{"rendered":"https:\/\/www.nstda.or.th\/openarchive\/?post_type=tnc_col_2585_item&#038;p=58649"},"modified":"2022-01-12T12:23:31","modified_gmt":"2022-01-12T05:23:31","slug":"tassanakajon-a","status":"publish","type":"tnc_col_2585_item","link":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/","title":{"rendered":"Tassanakajon A."},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","class_list":["post-58649","tnc_col_2585_item","type-tnc_col_2585_item","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tassanakajon A. - NSTDA Open Repository<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tassanakajon A. - NSTDA Open Repository\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA Open Repository\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-12T05:23:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/authors\\\/tassanakajon-a\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/authors\\\/tassanakajon-a\\\/\",\"name\":\"Tassanakajon A. - NSTDA Open Repository\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#website\"},\"datePublished\":\"2022-01-12T05:23:30+00:00\",\"dateModified\":\"2022-01-12T05:23:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/authors\\\/tassanakajon-a\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/authors\\\/tassanakajon-a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/authors\\\/tassanakajon-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Authors\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/authors\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tassanakajon A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\",\"name\":\"NSTDA Open Repository\",\"description\":\"NSTDA Open Repository is a digital open-access repository for NSTDA&#039;s research publications, including manuscripts, journal articles conference papers, reviews, and more. The publications are made available in the Repository on terms of Creative Commons License. You may read, download, share, and re-use for your research as long as you abide by the license under which an item has been released.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#organization\",\"name\":\"National Science and Technology Development Agency\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/cropped-cropped-aw-nstda-color-1-1.png\",\"contentUrl\":\"http:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/cropped-cropped-aw-nstda-color-1-1.png\",\"width\":2000,\"height\":625,\"caption\":\"National Science and Technology Development Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tassanakajon A. - NSTDA Open Repository","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/","og_locale":"en_US","og_type":"article","og_title":"Tassanakajon A. - NSTDA Open Repository","og_url":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/","og_site_name":"NSTDA Open Repository","article_modified_time":"2022-01-12T05:23:31+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/","url":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/","name":"Tassanakajon A. - NSTDA Open Repository","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#website"},"datePublished":"2022-01-12T05:23:30+00:00","dateModified":"2022-01-12T05:23:31+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/openarchive\/authors\/tassanakajon-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nstda.or.th\/openarchive\/"},{"@type":"ListItem","position":2,"name":"Authors","item":"https:\/\/www.nstda.or.th\/openarchive\/authors\/"},{"@type":"ListItem","position":3,"name":"Tassanakajon A."}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/openarchive\/#website","url":"https:\/\/www.nstda.or.th\/openarchive\/","name":"NSTDA Open Repository","description":"NSTDA Open Repository is a digital open-access repository for NSTDA&#039;s research publications, including manuscripts, journal articles conference papers, reviews, and more. The publications are made available in the Repository on terms of Creative Commons License. You may read, download, share, and re-use for your research as long as you abide by the license under which an item has been released.","publisher":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/openarchive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/openarchive\/#organization","name":"National Science and Technology Development Agency","url":"https:\/\/www.nstda.or.th\/openarchive\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/openarchive\/#\/schema\/logo\/image\/","url":"http:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","contentUrl":"http:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","width":2000,"height":625,"caption":"National Science and Technology Development Agency"},"image":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2585_item\/58649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2585_item"}],"about":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/types\/tnc_col_2585_item"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/comments?post=58649"}],"version-history":[{"count":0,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2585_item\/58649\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/media?parent=58649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}