{"id":117363,"date":"2023-04-11T14:55:38","date_gmt":"2023-04-11T07:55:38","guid":{"rendered":"http:\/\/10.223.74.30:38922\/openarchive\/?post_type=tnc_col_2494_item&#038;p=117363"},"modified":"2023-07-20T16:15:36","modified_gmt":"2023-07-20T09:15:36","slug":"model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production","status":"publish","type":"tnc_col_2494_item","link":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/","title":{"rendered":"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","class_list":["post-117363","tnc_col_2494_item","type-tnc_col_2494_item","status-publish","format-standard","hentry","tnc_tax_2222-agricultural-residues","tnc_tax_2222-biofuels","tnc_tax_2222-bioprocessing","tnc_tax_2222-demo-scale-simultaneous-saccharification-and-fermentation","tnc_tax_2222-enzymatic-hydrolysis","tnc_tax_2222-fed-batch-ssf","tnc_tax_2222-fermentation-technology","tnc_tax_2222-high-gravity","tnc_tax_2222-mathematical-modelling"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production - NSTDA Open Repository<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production - NSTDA Open Repository\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA Open Repository\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T09:15:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\\\/\",\"name\":\"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production - NSTDA Open Repository\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#website\"},\"datePublished\":\"2023-04-11T07:55:38+00:00\",\"dateModified\":\"2023-07-20T09:15:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NSTDA's Research Publications\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\",\"name\":\"NSTDA Open Repository\",\"description\":\"NSTDA Open Repository is a digital open-access repository for NSTDA&#039;s research publications, including manuscripts, journal articles conference papers, reviews, and more. The publications are made available in the Repository on terms of Creative Commons License. You may read, download, share, and re-use for your research as long as you abide by the license under which an item has been released.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#organization\",\"name\":\"National Science and Technology Development Agency\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/cropped-cropped-aw-nstda-color-1-1.png\",\"contentUrl\":\"http:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/cropped-cropped-aw-nstda-color-1-1.png\",\"width\":2000,\"height\":625,\"caption\":\"National Science and Technology Development Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production - NSTDA Open Repository","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/","og_locale":"en_US","og_type":"article","og_title":"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production - NSTDA Open Repository","og_url":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/","og_site_name":"NSTDA Open Repository","article_modified_time":"2023-07-20T09:15:36+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/","url":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/","name":"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production - NSTDA Open Repository","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#website"},"datePublished":"2023-04-11T07:55:38+00:00","dateModified":"2023-07-20T09:15:36+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/model-based-optimization-and-scale-up-of-multi-feed-simultaneous-saccharification-and-co-fermentation-of-steam-pre-treated-lignocellulose-enables-high-gravity-ethanol-production\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nstda.or.th\/openarchive\/"},{"@type":"ListItem","position":2,"name":"NSTDA's Research Publications","item":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/"},{"@type":"ListItem","position":3,"name":"Model-based optimization and scale-up of multi-feed simultaneous saccharification and co-fermentation of steam pre-treated lignocellulose enables high gravity ethanol production"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/openarchive\/#website","url":"https:\/\/www.nstda.or.th\/openarchive\/","name":"NSTDA Open Repository","description":"NSTDA Open Repository is a digital open-access repository for NSTDA&#039;s research publications, including manuscripts, journal articles conference papers, reviews, and more. The publications are made available in the Repository on terms of Creative Commons License. You may read, download, share, and re-use for your research as long as you abide by the license under which an item has been released.","publisher":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/openarchive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/openarchive\/#organization","name":"National Science and Technology Development Agency","url":"https:\/\/www.nstda.or.th\/openarchive\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/openarchive\/#\/schema\/logo\/image\/","url":"http:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","contentUrl":"http:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","width":2000,"height":625,"caption":"National Science and Technology Development Agency"},"image":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item\/117363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item"}],"about":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/types\/tnc_col_2494_item"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/comments?post=117363"}],"version-history":[{"count":1,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item\/117363\/revisions"}],"predecessor-version":[{"id":164711,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item\/117363\/revisions\/164711"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/media?parent=117363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}