{"id":100518,"date":"2022-05-02T14:27:25","date_gmt":"2022-05-02T07:27:25","guid":{"rendered":"https:\/\/www.nstda.or.th\/openarchive\/?post_type=tnc_col_2494_item&#038;p=100518"},"modified":"2023-01-23T15:54:48","modified_gmt":"2023-01-23T08:54:48","slug":"battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand","status":"publish","type":"tnc_col_2494_item","link":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/","title":{"rendered":"Battery sizing for electric vehicles based on real driving patterns in Thailand"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","class_list":["post-100518","tnc_col_2494_item","type-tnc_col_2494_item","status-publish","format-standard","hentry","tnc_tax_11166-n-a","tnc_tax_11164-n-a","tnc_tax_11162-n-a","tnc_tax_11156-n-a","tnc_tax_11150-battery-pack","tnc_tax_11150-battery-sizing","tnc_tax_11150-behavioral-research","tnc_tax_11150-buses","tnc_tax_11150-digital-storage","tnc_tax_11150-driving-cycle","tnc_tax_11150-electric-vehicles","tnc_tax_11150-electric-vehicles-evs","tnc_tax_11150-energy-consumption-analysis","tnc_tax_11150-energy-storage-systems","tnc_tax_11150-energy-utilization","tnc_tax_11150-internal-combustion-engine-vehicles","tnc_tax_11150-power-requirement","tnc_tax_11150-railroad-rolling-stock","tnc_tax_11150-traffic-conditions","tnc_tax_2222-battery-sizing","tnc_tax_2222-driving-cycle","tnc_tax_2222-electric-vehicle","tnc_tax_2222-energy-consumption"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Battery sizing for electric vehicles based on real driving patterns in Thailand - NSTDA Open Repository<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Battery sizing for electric vehicles based on real driving patterns in Thailand - NSTDA Open Repository\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA Open Repository\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T08:54:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\\\/\",\"name\":\"Battery sizing for electric vehicles based on real driving patterns in Thailand - NSTDA Open Repository\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#website\"},\"datePublished\":\"2022-05-02T07:27:25+00:00\",\"dateModified\":\"2023-01-23T08:54:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NSTDA's Research Publications\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/nstda-research-publications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Battery sizing for electric vehicles based on real driving patterns in Thailand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\",\"name\":\"NSTDA Open Repository\",\"description\":\"NSTDA Open Repository is a digital open-access repository for NSTDA&#039;s research publications, including manuscripts, journal articles conference papers, reviews, and more. The publications are made available in the Repository on terms of Creative Commons License. You may read, download, share, and re-use for your research as long as you abide by the license under which an item has been released.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#organization\",\"name\":\"National Science and Technology Development Agency\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/cropped-cropped-aw-nstda-color-1-1.png\",\"contentUrl\":\"http:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/cropped-cropped-aw-nstda-color-1-1.png\",\"width\":2000,\"height\":625,\"caption\":\"National Science and Technology Development Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/openarchive\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Battery sizing for electric vehicles based on real driving patterns in Thailand - NSTDA Open Repository","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/","og_locale":"en_US","og_type":"article","og_title":"Battery sizing for electric vehicles based on real driving patterns in Thailand - NSTDA Open Repository","og_url":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/","og_site_name":"NSTDA Open Repository","article_modified_time":"2023-01-23T08:54:48+00:00","og_image":[{"width":2000,"height":625,"url":"https:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/","url":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/","name":"Battery sizing for electric vehicles based on real driving patterns in Thailand - NSTDA Open Repository","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#website"},"datePublished":"2022-05-02T07:27:25+00:00","dateModified":"2023-01-23T08:54:48+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/battery-sizing-for-electric-vehicles-based-on-real-driving-patterns-in-thailand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nstda.or.th\/openarchive\/"},{"@type":"ListItem","position":2,"name":"NSTDA's Research Publications","item":"https:\/\/www.nstda.or.th\/openarchive\/nstda-research-publications\/"},{"@type":"ListItem","position":3,"name":"Battery sizing for electric vehicles based on real driving patterns in Thailand"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/openarchive\/#website","url":"https:\/\/www.nstda.or.th\/openarchive\/","name":"NSTDA Open Repository","description":"NSTDA Open Repository is a digital open-access repository for NSTDA&#039;s research publications, including manuscripts, journal articles conference papers, reviews, and more. The publications are made available in the Repository on terms of Creative Commons License. You may read, download, share, and re-use for your research as long as you abide by the license under which an item has been released.","publisher":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/openarchive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/openarchive\/#organization","name":"National Science and Technology Development Agency","url":"https:\/\/www.nstda.or.th\/openarchive\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/openarchive\/#\/schema\/logo\/image\/","url":"http:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","contentUrl":"http:\/\/www.nstda.or.th\/openarchive\/wp-content\/uploads\/2019\/02\/cropped-cropped-aw-nstda-color-1-1.png","width":2000,"height":625,"caption":"National Science and Technology Development Agency"},"image":{"@id":"https:\/\/www.nstda.or.th\/openarchive\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item\/100518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item"}],"about":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/types\/tnc_col_2494_item"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/comments?post=100518"}],"version-history":[{"count":1,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item\/100518\/revisions"}],"predecessor-version":[{"id":103177,"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/tnc_col_2494_item\/100518\/revisions\/103177"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/openarchive\/wp-json\/wp\/v2\/media?parent=100518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}