{"id":34,"date":"2025-01-18T12:21:28","date_gmt":"2025-01-18T05:21:28","guid":{"rendered":"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/"},"modified":"2025-03-28T18:49:29","modified_gmt":"2025-03-28T11:49:29","slug":"open-house","status":"publish","type":"page","link":"https:\/\/www.nstda.or.th\/nac\/2025\/open-house\/","title":{"rendered":"Open House"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"34\" class=\"elementor elementor-34\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64c969d e-con-full e-flex e-con e-parent\" data-id=\"64c969d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-99ff07c e-con-full e-flex e-con e-child\" data-id=\"99ff07c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-8609fef e-con-full e-flex e-con e-child\" data-id=\"8609fef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9579851 elementor-widget elementor-widget-image\" data-id=\"9579851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"976\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/baner-Open-House-1920x1080-03-1024x976.webp\" class=\"attachment-large size-large wp-image-1786\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/baner-Open-House-1920x1080-03-1024x976.webp 1024w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/baner-Open-House-1920x1080-03-300x286.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/baner-Open-House-1920x1080-03-768x732.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/baner-Open-House-1920x1080-03-1536x1464.webp 1536w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/baner-Open-House-1920x1080-03.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e499d37 e-con-full e-flex e-con e-child\" data-id=\"e499d37\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f466da elementor-widget elementor-widget-heading\" data-id=\"9f466da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07 STIST <br>\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7da191 elementor-widget elementor-widget-heading\" data-id=\"f7da191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">STIST: S&amp;T Implementation for Sustainable Thailand<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2258d1 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"e2258d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ee8a3 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"09ee8a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e84f480 e-con-full e-flex e-con e-child\" data-id=\"e84f480\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8fe009 elementor-widget elementor-widget-heading\" data-id=\"a8fe009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">26 \u0e41\u0e25\u0e30 28 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<!-- dce invisible element e04ab99 -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1636501 e-flex e-con-boxed e-con e-parent\" data-id=\"1636501\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-213c8c1 e-flex e-con-boxed e-con e-child\" data-id=\"213c8c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d684810 e-con-full e-flex e-con e-child\" data-id=\"d684810\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab6dd8b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ab6dd8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ed326a e-con-full e-flex e-con e-child\" data-id=\"2ed326a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ccf055 elementor-widget elementor-widget-heading\" data-id=\"2ccf055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e04\u0e37\u0e2d \u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Open House \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-307ec66 elementor-widget elementor-widget-text-editor\" data-id=\"307ec66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22 \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e2d\u0e27\u0e17.) \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Open House \u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e0a\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22 \u0e08\u0e32\u0e01 \u0e2a\u0e27\u0e17\u0e0a. \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e2a\u0e39\u0e48\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e37ef3a e-flex e-con-boxed e-con e-parent\" data-id=\"e37ef3a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dafed0e e-con-full e-flex e-con e-child\" data-id=\"dafed0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6474b6b elementor-tabs-view-horizontal elementor-widget elementor-widget-tp-tabs-tours\" data-id=\"6474b6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-tabs-tours.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"theplus-tabs-wrapper  elementor-tabs   swiper-container swiper-free-mode   \" id=\"tabs6a57b1087039d\" data-tabs-id=\"tabs6a57b1087039d\"  data-connection=\"\"   data-tab-default=\"0\" data-tab-hover=\"no\"data-swiper-loop ='no'  role=\"tablist\"><div class=\"theplus-tabs-nav-wrapper elementor-tabs-wrapper text-left align-top swiper-wrapper  \"><ul class=\"plus-tabs-nav  nav-tab-underline   swiper-slide swiper-slide-active \"><li class=\"\"><div id=\"elementor-tab-title-1051\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"1\" tabindex=\"1051\" role=\"tab\" aria-controls=\"elementor-tab-content-1051\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-calendar\"><\/i><\/span><span>26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-1052\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"2\" tabindex=\"1052\" role=\"tab\" aria-controls=\"elementor-tab-content-1052\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-calendar\"><\/i><\/span><span>28 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21<\/span><\/div><\/li><\/ul><\/div><div class=\"theplus-tabs-content-wrapper  elementor-tabs-content-wrapper\"><div class=\"elementor-tab-title elementor-tab-mobile-title text-left \" tabindex=\"1051\" data-tab=\"1\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-calendar\"><\/i><\/span><span>26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"1\" role=\"tabpanel\"><div class=\"plus-content-editor\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"2359\" class=\"elementor elementor-2359\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8da99b2 e-flex e-con-boxed e-con e-parent\" data-id=\"8da99b2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da0ee29 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"da0ee29\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf0f9c elementor-widget elementor-widget-heading\" data-id=\"eaf0f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e15\u0e32\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-478b8d2 e-grid e-con-full e-con e-child\" data-id=\"478b8d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-c55e63c e-con-full e-flex e-con e-child\" data-id=\"c55e63c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc65bc elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"9cc65bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b10883b66   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/ai\/\"><h3 class=\"addbanner_title\">A1 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b10883b50 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/ai\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e96a73a e-con-full e-flex e-con e-child\" data-id=\"e96a73a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e271e65 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"e271e65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b10884a88   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/env\/\"><h3 class=\"addbanner_title\">A2 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b10884a69 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/env\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f6b978 e-con-full e-flex e-con e-child\" data-id=\"9f6b978\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aac1633 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"aac1633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108879fa   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/foods\/\"><h3 class=\"addbanner_title\">A3 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108879e9 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/foods\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bce2ca8 e-con-full e-flex e-con e-child\" data-id=\"bce2ca8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-737ba25 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"737ba25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b10899825   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/health-wellness\/\"><h3 class=\"addbanner_title\">A4 - \u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b1089980e button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/health-wellness\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b2a514 e-con-full e-flex e-con e-child\" data-id=\"9b2a514\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f82d097 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"f82d097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b1089ac99   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/cosmetic\/\"><h3 class=\"addbanner_title\">A5 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b1089ac87 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/cosmetic\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5eb19a7 e-con-full e-flex e-con e-child\" data-id=\"5eb19a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20c1edb elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"20c1edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b1089bdd3   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-agri\/\"><h3 class=\"addbanner_title\">A6 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b1089bdbf button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-agri\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34026ec e-con-full e-flex e-con e-child\" data-id=\"34026ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cde7d37 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"cde7d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b1089d12d   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-industry\/\"><h3 class=\"addbanner_title\">A7 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b1089d10c button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-industry\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36020f1 e-con-full e-flex e-con e-child\" data-id=\"36020f1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b57997f elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"b57997f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b1089dfc4   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-1\/\"><h3 class=\"addbanner_title\">A8 - From Concept to Certification<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b1089dfb4 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-1\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d01d5d1 e-con-full e-flex e-con e-child\" data-id=\"d01d5d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e220fdf elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"e220fdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b1089effd   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-2\/\"><h3 class=\"addbanner_title\">A9 - Quality Assurance  in Action<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b1089efec button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-2\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-413fa0e e-con-full e-flex e-con e-child\" data-id=\"413fa0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d19333 plus-border-yes elementor-widget elementor-widget-tp-table\" data-id=\"1d19333\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div itemscope class=\"plus-table-wrapper   tp-table-mobresswipe\" itemtype=\"http:\/\/schema.org\/Table\">\r\n\r\n\t\t\t\t<table id=\"plus-table-id-1d19333\" class=\"plus-table plus-text-break plus-column-rules\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<thead> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr class=\"plus-table-row\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a2351\"data-sort=\"0\" class=\"sort-this elementor-repeater-item-e682d03 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e40\u0e0a\u0e49\u0e32<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a235b\"data-sort=\"1\" class=\"sort-this elementor-repeater-item-3d4b63f plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A1<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a2362\"data-sort=\"2\" class=\"sort-this elementor-repeater-item-71f1ce0 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A2<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a2367\"data-sort=\"3\" class=\"sort-this elementor-repeater-item-44d149d plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A3<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a236d\"data-sort=\"4\" class=\"sort-this elementor-repeater-item-563070e plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A4<br>\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a2373\"data-sort=\"5\" class=\"sort-this elementor-repeater-item-d77a970 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A5<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a2379\"data-sort=\"6\" class=\"sort-this elementor-repeater-item-4f25c37 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A6<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108a237e\"data-sort=\"7\" class=\"sort-this elementor-repeater-item-8199fcd plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A7<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/thead> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<tbody>\r\n\t\t\t\t\t\t\t<!-- ROWS -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a238a\"class=\"plus-table-col elementor-repeater-item-cd02bd4\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">8.30-9.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a23b4\"class=\"plus-table-col elementor-repeater-item-687d174\" colspan=\"7\" data-title=\"A1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a23de\"class=\"plus-table-col elementor-repeater-item-118543a\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">9.00-9.30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a23ed\"class=\"plus-table-col elementor-repeater-item-ce53ba5\" colspan=\"7\" data-title=\"A1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e27\u0e17 (INC2 C)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2406\"class=\"plus-table-col elementor-repeater-item-c65d18a\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">9.30-10.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2416\"class=\"plus-table-col elementor-repeater-item-3d66fca\" data-title=\"A1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e01\u0e23\u0e32\u0e1f\u0e35\u0e19 (GRP)- cutting edge (INC2 D, Fl. 5)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2429\"class=\"plus-table-col elementor-repeater-item-a4a3584\" data-title=\"A2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (TBRC, INC2, x Fl. 8)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a243b\"class=\"plus-table-col elementor-repeater-item-8ec8bbe\" data-title=\"A3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Food Innopolis (INC 2, Fl. 1)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a244d\"class=\"plus-table-col elementor-repeater-item-494f1d9\" data-title=\"A4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e0a\u0e38\u0e14\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e2b\u0e21\u0e49\u0e2d\u0e19\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e19\u0e44\u0e2d\u0e19\u0e49\u0e33 (RNM) (INC2, Fl. X)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a245f\"class=\"plus-table-col elementor-repeater-item-cb691f6\" data-title=\"A5&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e19\u0e32\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 <br>(INC2B \u0e0a\u0e31\u0e49\u0e19 2) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a247e\"class=\"plus-table-col elementor-repeater-item-51e661d\" data-title=\"A6&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Agri PV + HandySense\/  Agrivoltaic ( NECTEC pilot plant) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2492\"class=\"plus-table-col elementor-repeater-item-9836ef2\" data-title=\"A7&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">virtual EECi \/ Thailand i4.0\n(NECTEC pilot plant)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a24a7\"class=\"plus-table-col elementor-repeater-item-15cc1ea\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">10.10-10.40<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a24b5\"class=\"plus-table-col elementor-repeater-item-5ebfae6\" data-title=\"A1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">ThaiSC\n (INC 2, Fl.1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a24ce\"class=\"plus-table-col elementor-repeater-item-5dbd551\" rowspan=\"2\" data-title=\"A2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 NANO \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\n (INC2, Fl. X)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a24df\"class=\"plus-table-col elementor-repeater-item-adfad67\" data-title=\"A3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Integrative Biorefinery Laboratory (IBL), INC2 9 FL\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a24ef\"class=\"plus-table-col elementor-repeater-item-c3e493e\" data-title=\"A4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">TBES \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30 Biocompatibility \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c (INC2C, Fl. 6)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2503\"class=\"plus-table-col elementor-repeater-item-5bd45dc\" data-title=\"A5&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e (lab NSB, INC2B, FL. 2)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2514\"class=\"plus-table-col elementor-repeater-item-c231af6\" data-title=\"A6&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NPV \n(Biotec Pilot Plant) \n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a2523\"class=\"plus-table-col elementor-repeater-item-af2a726\" data-title=\"A7&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">SMC \n(NECTEC pilot plant)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a253d\"class=\"plus-table-col elementor-repeater-item-8d1c97f\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">10.50-11.20<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a254a\"class=\"plus-table-col elementor-repeater-item-c680634\" rowspan=\"2\" data-title=\"A1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\"> \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19 \u0e2a\u0e27\u0e17\u0e0a. \u0e14\u0e49\u0e32\u0e19 AI\n (CC , Fl. 1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a255c\"class=\"plus-table-col elementor-repeater-item-42b7d7e\" rowspan=\"2\" data-title=\"A2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Biotec Bioprocessing Facility, Biotec pilot plant\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a256c\"class=\"plus-table-col elementor-repeater-item-26c4a72\" data-title=\"A3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">CTEC \nBio Compatibility (INC2, Fl. 7)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a257b\"class=\"plus-table-col elementor-repeater-item-db882f6\" data-title=\"A4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NCTC \n(INC2, Fl.3)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a258b\"class=\"plus-table-col elementor-repeater-item-eb48f80\" rowspan=\"2\" data-title=\"A5&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Plant factory \n(INC 2, Fl. 7)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a259b\"class=\"plus-table-col elementor-repeater-item-f9836eb\" rowspan=\"2\" data-title=\"A6&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NFED\n(\u0e02\u0e49\u0e32\u0e07 SCG)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"6\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a25b2\"class=\"plus-table-col elementor-repeater-item-68176bc\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">11.30-12.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a25bf\"class=\"plus-table-col elementor-repeater-item-aca26d9\" data-title=\"A1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e04\u0e25\u0e31\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\n(National BIO Bank :NBT INC2, x  Fl. 1)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a25ce\"class=\"plus-table-col elementor-repeater-item-03d5bef\" data-title=\"A2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Wearable Tech Lab (MTEC pilot plant)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108a25de\"class=\"plus-table-col elementor-repeater-item-9cec610\" data-title=\"A3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (TBRC, INC2, x Fl. 8)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tbody>\r\n\t\t\t\t<\/table>\r\n\r\n\t\t\t<\/div> \r\n\t\t\t<style>#plus-table-id-1d19333 th,#plus-table-id-1d19333 th .plus-table__text{ margin:0 auto;text-align:center;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd19ec5 e-con-full e-flex e-con e-child\" data-id=\"cd19ec5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c02a499 plus-border-yes elementor-widget elementor-widget-tp-table\" data-id=\"c02a499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div itemscope class=\"plus-table-wrapper   tp-table-mobresswipe\" itemtype=\"http:\/\/schema.org\/Table\">\r\n\r\n\t\t\t\t<table id=\"plus-table-id-c02a499\" class=\"plus-table plus-text-break plus-column-rules\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<thead> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr class=\"plus-table-row\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108b20d4\"data-sort=\"0\" class=\"sort-this elementor-repeater-item-e682d03 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e1a\u0e48\u0e32\u0e22<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108b20de\"data-sort=\"1\" class=\"sort-this elementor-repeater-item-3d4b63f plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A8<br>From Concept to Certification<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108b20e4\"data-sort=\"2\" class=\"sort-this elementor-repeater-item-71f1ce0 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">A9<br>Quality Assurance in Action<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/thead> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<tbody>\r\n\t\t\t\t\t\t\t<!-- ROWS -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b20f2\"class=\"plus-table-col elementor-repeater-item-cd02bd4\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">13.30-14.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b2139\"class=\"plus-table-col elementor-repeater-item-687d174\" colspan=\"2\" data-title=\"A8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 (NQI \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e14\u0e2a\u0e2d\u0e1a)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b216d\"class=\"plus-table-col elementor-repeater-item-118543a\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">14.00-14.25<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b217b\"class=\"plus-table-col elementor-repeater-item-ce53ba5\" colspan=\"2\" data-title=\"A8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e27\u0e17 (INC2 C)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b2197\"class=\"plus-table-col elementor-repeater-item-c65d18a\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">14.30-15.30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b21a4\"class=\"plus-table-col elementor-repeater-item-3d66fca\" data-title=\"A8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NFED\n(\u0e02\u0e49\u0e32\u0e07 SCG)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b21b7\"class=\"plus-table-col elementor-repeater-item-a4a3584\" data-title=\"A9&lt;br&gt;Quality Assurance in Action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NCTC\n(INC2, Fl.3) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b21ce\"class=\"plus-table-col elementor-repeater-item-15cc1ea\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">15.35-16.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b21da\"class=\"plus-table-col elementor-repeater-item-5ebfae6\" data-title=\"A8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">PTEC (\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1b\u0e34\u0e14\u0e01\u0e31\u0e49\u0e19\u0e04\u0e25\u0e37\u0e48\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e44\u0e23\u0e49\u0e04\u0e25\u0e37\u0e48\u0e19\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19 PTEC3, A5)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b21ed\"class=\"plus-table-col elementor-repeater-item-adfad67\" data-title=\"A9&lt;br&gt;Quality Assurance in Action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">CTEC \n(INC2, Fl. 7)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b2202\"class=\"plus-table-col elementor-repeater-item-8d1c97f\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">16.00-16.30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b2213\"class=\"plus-table-col elementor-repeater-item-c680634\" data-title=\"A8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\n(CC , Fl. 1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108b2229\"class=\"plus-table-col elementor-repeater-item-d055488\" data-title=\"A9&lt;br&gt;Quality Assurance in Action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\n(CC , Fl. 1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tbody>\r\n\t\t\t\t<\/table>\r\n\r\n\t\t\t<\/div> \r\n\t\t\t<style>#plus-table-id-c02a499 th,#plus-table-id-c02a499 th .plus-table__text{ margin:0 auto;text-align:center;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-left \" tabindex=\"1052\" data-tab=\"2\" role=\"tab\"><span class=\"tab-icon-wrap\" aria-hidden=\"true\"><i class=\"tab-icon fa fa-calendar\"><\/i><\/span><span>28 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"2\" role=\"tabpanel\"><div class=\"plus-content-editor\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"2362\" class=\"elementor elementor-2362\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-941ad3d e-flex e-con-boxed e-con e-parent\" data-id=\"941ad3d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7883519 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"7883519\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cde09b6 elementor-widget elementor-widget-heading\" data-id=\"cde09b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e15\u0e32\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-304411e e-grid e-con-full e-con e-child\" data-id=\"304411e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-79f84a7 e-con-full e-flex e-con e-child\" data-id=\"79f84a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77128a7 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"77128a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b4748   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/ai\/\"><h3 class=\"addbanner_title\">B1 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b472f button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/ai\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-01-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2b6277 e-con-full e-flex e-con e-child\" data-id=\"b2b6277\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b63ce0e elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"b63ce0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b53e6   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/env\/\"><h3 class=\"addbanner_title\">B2 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b53d6 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/env\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-01-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9cdaeb3 e-con-full e-flex e-con e-child\" data-id=\"9cdaeb3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40eae2d elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"40eae2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b5f66   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/foods\/\"><h3 class=\"addbanner_title\">B3 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b5f57 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/foods\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image-03-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d90ed20 e-con-full e-flex e-con e-child\" data-id=\"d90ed20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd4a96 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"2fd4a96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b6b13   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/health-wellness\/\"><h3 class=\"addbanner_title\">B4 - \u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b6b04 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/health-wellness\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-02-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-350f358 e-con-full e-flex e-con e-child\" data-id=\"350f358\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9785f51 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"9785f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b76ac   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/cosmetic\/\"><h3 class=\"addbanner_title\">B5 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b769d button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/cosmetic\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-03-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3145012 e-con-full e-flex e-con e-child\" data-id=\"3145012\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1de7e77 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"1de7e77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b8234   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-agri\/\"><h3 class=\"addbanner_title\">B6 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b8225 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-agri\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-04-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc829de e-con-full e-flex e-con e-child\" data-id=\"dc829de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82b1e08 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"82b1e08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108b8da3   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-industry\/\"><h3 class=\"addbanner_title\">B7 - \u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108b8d94 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/smart-industry\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-05-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d7dae8 e-con-full e-flex e-con e-child\" data-id=\"1d7dae8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acdf0a6 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"acdf0a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108caf56   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-1\/\"><h3 class=\"addbanner_title\">B8 - From Concept to Certification<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108caf42 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-1\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-06-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ebe3acb e-con-full e-flex e-con e-child\" data-id=\"ebe3acb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60b9b64 elementor-widget elementor-widget-tp_advertisement_banner\" data-id=\"60b9b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp_advertisement_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content_hover_effect  \" ><div class=\"pt_plus_addbanner add-banner-style-1 addbanner-image-blur addbanner-fade-out image-loaded box_saddow_addbanner add-banner6a57b108cbbc3   \" > <div class=\"addbanner-block\" ><div class=\"addbanner_inner text-left\"><div class=\"top-left\"><div class=\"content-level2\"><div class=\"content-level3\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-2\/\"><h3 class=\"addbanner_title\">B9 - Quality Assurance  in Action<\/h3><\/a><div class=\"pt-plus-button-wrapper\"><div class=\"button_parallax\"><div class=\"ts-button\"><div class=\"pt_plus_button btn6a57b108cbbb3 button-style-7 \"><div class=\"animted-content-inner\"><a href=\"http:\/\/www.nstda.or.th\/nac\/2025\/open-house\/nqi-2\/\" class=\"button-link-wrap \" role=\"button\" data-hover=\"\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\">\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21<span class=\"btn-arrow\"><\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"addbanner_inner_img \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07.webp\" class=\"info_img\" alt=\"\" srcset=\"https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07.webp 1000w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-300x300.webp 300w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-150x150.webp 150w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-768x768.webp 768w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-700x700.webp 700w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-70x70.webp 70w, https:\/\/www.nstda.or.th\/nac\/2025\/wp-content\/uploads\/2025\/02\/Open_house_route_image_re-07-100x100.webp 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"entry-thumb\"><div class=\"entry-hover \"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed099d0 e-con-full e-flex e-con e-child\" data-id=\"ed099d0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa78f0f plus-border-yes elementor-widget elementor-widget-tp-table\" data-id=\"fa78f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div itemscope class=\"plus-table-wrapper   tp-table-mobresswipe\" itemtype=\"http:\/\/schema.org\/Table\">\r\n\r\n\t\t\t\t<table id=\"plus-table-id-fa78f0f\" class=\"plus-table plus-text-break plus-column-rules\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<thead> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr class=\"plus-table-row\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd0a\"data-sort=\"0\" class=\"sort-this elementor-repeater-item-e682d03 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e40\u0e0a\u0e49\u0e32<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd14\"data-sort=\"1\" class=\"sort-this elementor-repeater-item-3d4b63f plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B1<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd1b\"data-sort=\"2\" class=\"sort-this elementor-repeater-item-71f1ce0 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B2<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd22\"data-sort=\"3\" class=\"sort-this elementor-repeater-item-44d149d plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B3<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd29\"data-sort=\"4\" class=\"sort-this elementor-repeater-item-563070e plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B4<br>\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd2e\"data-sort=\"5\" class=\"sort-this elementor-repeater-item-d77a970 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B5<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd35\"data-sort=\"6\" class=\"sort-this elementor-repeater-item-4f25c37 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B6<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108ccd3b\"data-sort=\"7\" class=\"sort-this elementor-repeater-item-8199fcd plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B7<br>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/thead> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<tbody>\r\n\t\t\t\t\t\t\t<!-- ROWS -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccd49\"class=\"plus-table-col elementor-repeater-item-cd02bd4\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">8.30-9.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccd86\"class=\"plus-table-col elementor-repeater-item-687d174\" colspan=\"7\" data-title=\"B1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccdaf\"class=\"plus-table-col elementor-repeater-item-118543a\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">9.00-9.30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccdc0\"class=\"plus-table-col elementor-repeater-item-ce53ba5\" colspan=\"7\" data-title=\"B1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e27\u0e17 (INC2 C)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccdd9\"class=\"plus-table-col elementor-repeater-item-c65d18a\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">9.30-10.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccde8\"class=\"plus-table-col elementor-repeater-item-3d66fca\" data-title=\"B1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e01\u0e23\u0e32\u0e1f\u0e35\u0e19 (GRP)- cutting edge (INC2 D, Fl. 5)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccdfc\"class=\"plus-table-col elementor-repeater-item-a4a3584\" data-title=\"B2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (TBRC, INC2, x Fl. 8)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce11\"class=\"plus-table-col elementor-repeater-item-8ec8bbe\" data-title=\"B3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Food Innopolis (INC 2, Fl. 1)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce23\"class=\"plus-table-col elementor-repeater-item-494f1d9\" data-title=\"B4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e0a\u0e38\u0e14\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e2b\u0e21\u0e49\u0e2d\u0e19\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e19\u0e44\u0e2d\u0e19\u0e49\u0e33 (RNM) (INC2, Fl. X)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce36\"class=\"plus-table-col elementor-repeater-item-cb691f6\" data-title=\"B5&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e19\u0e32\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 <br>(INC2B \u0e0a\u0e31\u0e49\u0e19 2) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce5f\"class=\"plus-table-col elementor-repeater-item-51e661d\" data-title=\"B6&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Agri PV + HandySense\/  Agrivoltaic ( NECTEC pilot plant) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce73\"class=\"plus-table-col elementor-repeater-item-9836ef2\" data-title=\"B7&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">virtual EECi \/ Thailand i4.0\n(NECTEC pilot plant)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce8b\"class=\"plus-table-col elementor-repeater-item-15cc1ea\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">10.10-10.40<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cce99\"class=\"plus-table-col elementor-repeater-item-5ebfae6\" data-title=\"B1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">ThaiSC\n (INC 2, Fl.1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccead\"class=\"plus-table-col elementor-repeater-item-4323644\" rowspan=\"2\" data-title=\"B2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 NANO \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\n (INC2, Fl. X)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccecd\"class=\"plus-table-col elementor-repeater-item-adfad67\" data-title=\"B3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Integrative Biorefinery Laboratory (IBL), INC2 9 FL\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccee0\"class=\"plus-table-col elementor-repeater-item-c3e493e\" data-title=\"B4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22 TBES (INC2C, Fl 6) \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccef3\"class=\"plus-table-col elementor-repeater-item-5bd45dc\" data-title=\"B5&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e (lab NSB, INC2B, FL. 2)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf05\"class=\"plus-table-col elementor-repeater-item-c231af6\" data-title=\"B6&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NPV \n(Biotec Pilot Plant) \n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf16\"class=\"plus-table-col elementor-repeater-item-af2a726\" data-title=\"B7&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">SMC \n(NECTEC pilot plant)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf2e\"class=\"plus-table-col elementor-repeater-item-8d1c97f\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">10.50-11.20<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf3b\"class=\"plus-table-col elementor-repeater-item-c680634\" rowspan=\"2\" data-title=\"B1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\"> \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19 \u0e2a\u0e27\u0e17\u0e0a. \u0e14\u0e49\u0e32\u0e19 AI\n (CC , Fl. 1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf4f\"class=\"plus-table-col elementor-repeater-item-42b7d7e\" rowspan=\"2\" data-title=\"B2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Biotec Bioprocessing Facility, Biotec pilot plant\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf60\"class=\"plus-table-col elementor-repeater-item-26c4a72\" data-title=\"B3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">CTEC \nBio Compatibility (INC2, Fl. 7)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf72\"class=\"plus-table-col elementor-repeater-item-db882f6\" data-title=\"B4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NCTC \n(INC2, Fl.3)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf83\"class=\"plus-table-col elementor-repeater-item-eb48f80\" data-title=\"B5&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Plant factory \n(INC 2, Fl. 7)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccf94\"class=\"plus-table-col elementor-repeater-item-f9836eb\" rowspan=\"2\" data-title=\"B6&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NFED\n(\u0e02\u0e49\u0e32\u0e07 SCG)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"6\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccfa9\"class=\"plus-table-col elementor-repeater-item-68176bc\" data-title=\"\u0e40\u0e0a\u0e49\u0e32\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">11.30-12.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccfb6\"class=\"plus-table-col elementor-repeater-item-aca26d9\" data-title=\"B1&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI)\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e04\u0e25\u0e31\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\n(National BIO Bank :NBT INC2, x  Fl. 1)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccfc7\"class=\"plus-table-col elementor-repeater-item-03d5bef\" data-title=\"B2&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">Wearable Tech Lab (MTEC pilot plant)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccfd8\"class=\"plus-table-col elementor-repeater-item-9cec610\" data-title=\"B3&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e0a\u0e35\u0e27\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (TBRC, INC2, x Fl. 8)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108ccfe8\"class=\"plus-table-col elementor-repeater-item-aa1db50\" data-title=\"B4&lt;br&gt;\u0e01\u0e25\u0e38\u0e48\u0e21 Wellness Tech  \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e39\u0e48 Thailand Health Hub\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NOC (INC 2A, Fl.6) (\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 28 \u0e21\u0e35.\u0e04 68 )<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tbody>\r\n\t\t\t\t<\/table>\r\n\r\n\t\t\t<\/div> \r\n\t\t\t<style>#plus-table-id-fa78f0f th,#plus-table-id-fa78f0f th .plus-table__text{ margin:0 auto;text-align:center;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe1a73d e-con-full e-flex e-con e-child\" data-id=\"fe1a73d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51c22aa plus-border-yes elementor-widget elementor-widget-tp-table\" data-id=\"51c22aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div itemscope class=\"plus-table-wrapper   tp-table-mobresswipe\" itemtype=\"http:\/\/schema.org\/Table\">\r\n\r\n\t\t\t\t<table id=\"plus-table-id-51c22aa\" class=\"plus-table plus-text-break plus-column-rules\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<thead> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr class=\"plus-table-row\"> \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108cdd76\"data-sort=\"0\" class=\"sort-this elementor-repeater-item-e682d03 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e1a\u0e48\u0e32\u0e22<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108cdd81\"data-sort=\"1\" class=\"sort-this elementor-repeater-item-3d4b63f plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B8<br>From Concept to Certification<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th id=\"tooltip6a57b108cdd88\"data-sort=\"2\" class=\"sort-this elementor-repeater-item-71f1ce0 plus-table-col\" data-local=\"true\"  scope=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"sort-style\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">B9<br>Quality Assurance in Action<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span> \r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/th>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/thead> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<tbody>\r\n\t\t\t\t\t\t\t<!-- ROWS -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cdd95\"class=\"plus-table-col elementor-repeater-item-cd02bd4\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">13.30-14.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cddc2\"class=\"plus-table-col elementor-repeater-item-687d174\" colspan=\"2\" data-title=\"B8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 (NQI \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e14\u0e2a\u0e2d\u0e1a)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"2\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cdde8\"class=\"plus-table-col elementor-repeater-item-118543a\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">14.00-14.25<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cddf8\"class=\"plus-table-col elementor-repeater-item-ce53ba5\" colspan=\"2\" data-title=\"B8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e27\u0e17 (INC2 C)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"3\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde11\"class=\"plus-table-col elementor-repeater-item-c65d18a\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">14.30-15.30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde20\"class=\"plus-table-col elementor-repeater-item-3d66fca\" data-title=\"B8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NFED\n(\u0e02\u0e49\u0e32\u0e07 SCG)<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde33\"class=\"plus-table-col elementor-repeater-item-a4a3584\" data-title=\"B9&lt;br&gt;Quality Assurance in Action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">NCTC\n(INC2, Fl.3) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"4\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde49\"class=\"plus-table-col elementor-repeater-item-15cc1ea\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">15.35-16.00<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde61\"class=\"plus-table-col elementor-repeater-item-5ebfae6\" data-title=\"B8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">PTEC (\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1b\u0e34\u0e14\u0e01\u0e31\u0e49\u0e19\u0e04\u0e25\u0e37\u0e48\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e44\u0e23\u0e49\u0e04\u0e25\u0e37\u0e48\u0e19\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19 PTEC3, A5)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde78\"class=\"plus-table-col elementor-repeater-item-adfad67\" data-title=\"B9&lt;br&gt;Quality Assurance in Action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">CTEC \n(INC2, Fl. 7)\n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr><tr data-entry=\"5\" class=\"plus-table-row\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde8e\"class=\"plus-table-col elementor-repeater-item-8d1c97f\" data-title=\"\u0e1a\u0e48\u0e32\u0e22\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">16.00-16.30<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cde9c\"class=\"plus-table-col elementor-repeater-item-c680634\" data-title=\"B8&lt;br&gt;From Concept to Certification\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\n(CC , Fl. 1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<td id=\"tooltip6a57b108cdeaf\"class=\"plus-table-col elementor-repeater-item-d055488\" data-title=\"B9&lt;br&gt;Quality Assurance in Action\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"plus-table__text-inner\">\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\n(CC , Fl. 1) <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/td>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tbody>\r\n\t\t\t\t<\/table>\r\n\r\n\t\t\t<\/div> \r\n\t\t\t<style>#plus-table-id-51c22aa th,#plus-table-id-51c22aa th .plus-table__text{ margin:0 auto;text-align:center;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07 STIST \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 STIST: S&#038;T Implementation for Sustainable Thailand \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 26 \u0e41\u0e25\u0e30 28 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e04\u0e37\u0e2d \u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Open House \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22 \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e2d\u0e27\u0e17.) \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Open House \u0e40\u0e1b\u0e34\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e0a\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22 \u0e08\u0e32\u0e01 \u0e2a\u0e27\u0e17\u0e0a. \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e2a\u0e39\u0e48\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d 26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 28 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 26 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e15\u0e32\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 A1 &#8211; \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI) \u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-34","page","type-page","status-publish","hentry"],"blocksy_meta":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"dev-webeasy","author_link":"https:\/\/www.nstda.or.th\/nac\/2025\/author\/webeasy-dev\/"},"comment_info":"","_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/pages\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":7,"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/pages\/34\/revisions"}],"predecessor-version":[{"id":7736,"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/pages\/34\/revisions\/7736"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/nac\/2025\/wp-json\/wp\/v2\/media?parent=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}