{"id":84252,"date":"2026-05-13T17:01:21","date_gmt":"2026-05-13T10:01:21","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/?page_id=84252"},"modified":"2026-05-14T15:12:11","modified_gmt":"2026-05-14T08:12:11","slug":"moac","status":"publish","type":"page","link":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/","title":{"rendered":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"84252\" class=\"elementor elementor-84252\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d3a985 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3d3a985\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da09d7a\" data-id=\"da09d7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7bff5c elementor-widget elementor-widget-heading\" data-id=\"f7bff5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e38e1bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e38e1bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dac2eb6\" data-id=\"dac2eb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce0076 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"3ce0076\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e37\u0e0a\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 (Precision Agriculture and Sustainable Crop Production)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed5fa2d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ed5fa2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5667cb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5667cb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-74fe081\" data-id=\"74fe081\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-948c00e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"948c00e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P01.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 1: \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e44\u0e17\u0e22 \u0e1c\u0e2a\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P01.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 1: \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e44\u0e17\u0e22 \u0e1c\u0e2a\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a8657e\" data-id=\"1a8657e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-194e832 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"194e832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P02.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07\u0e27\u0e31\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P02.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07\u0e27\u0e31\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3740d96\" data-id=\"3740d96\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec9c135 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ec9c135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P03.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 1 \u0e41\u0e25\u0e30\u0e16\u0e31\u0e48\u0e27\u0e1d\u0e31\u0e01\u0e22\u0e32\u0e27\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P03.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 1 \u0e41\u0e25\u0e30\u0e16\u0e31\u0e48\u0e27\u0e1d\u0e31\u0e01\u0e22\u0e32\u0e27\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0660d4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0660d4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da42848\" data-id=\"da42848\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a96f5db elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"a96f5db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P04.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22 (\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01) \u201cNANO nCote (\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e04\u0e15)\u201d Controlled Release Fertilizer: CRF\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P04.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22 (\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01) \u201cNANO nCote (\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e04\u0e15)\u201d Controlled Release Fertilizer: CRF\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0333f4c\" data-id=\"0333f4c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2de336b elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2de336b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P06.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"ChelaPlant-Nano \u0e1b\u0e38\u0e4b\u0e22\u0e19\u0e32\u0e42\u0e19\u0e04\u0e35\u0e40\u0e25\u0e15\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e08\u0e32\u0e01\u0e2d\u0e19\u0e38\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P06.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tChelaPlant-Nano \u0e1b\u0e38\u0e4b\u0e22\u0e19\u0e32\u0e42\u0e19\u0e04\u0e35\u0e40\u0e25\u0e15\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e08\u0e32\u0e01\u0e2d\u0e19\u0e38\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da19f88\" data-id=\"da19f88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c89c5f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c89c5f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8692f2\" data-id=\"a8692f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdafcfd elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"cdafcfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 (Food, Health, and Functional Ingredients Innovation)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d6066 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"58d6066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aea73a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aea73a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-58c922b\" data-id=\"58c922b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b3a055 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3b3a055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P07.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e01\u0e32\u0e41\u0e1f\u0e2b\u0e21\u0e31\u0e01: \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P07.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e01\u0e32\u0e41\u0e1f\u0e2b\u0e21\u0e31\u0e01: \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-47524b1\" data-id=\"47524b1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ecb304 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2ecb304\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P08.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P08.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d14655f\" data-id=\"d14655f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca07347 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ca07347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P09.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e1c\u0e07\u0e2b\u0e21\u0e31\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c : \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e42\u0e04\u0e08\u0e34\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P09.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e1c\u0e07\u0e2b\u0e21\u0e31\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c : \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e42\u0e04\u0e08\u0e34\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5fea1d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5fea1d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cdfcdfe\" data-id=\"cdfcdfe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84f13eb elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"84f13eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P10.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e41\u0e25\u0e04\u0e42\u0e15\u0e41\u0e04\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c : \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P10.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e41\u0e25\u0e04\u0e42\u0e15\u0e41\u0e04\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c : \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-618e974\" data-id=\"618e974\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1b76a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7e1b76a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P11.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e42\u0e1e\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 : \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e02\u0e19\u0e32\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P11.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e42\u0e1e\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 : \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e02\u0e19\u0e32\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-10b88c1\" data-id=\"10b88c1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-173532f elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"173532f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P12.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Green Rice Biome: \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21\u0e21\u0e30\u0e25\u0e34\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P12.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tGreen Rice Biome: \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21\u0e21\u0e30\u0e25\u0e34\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24f2748 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24f2748\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-97e83ed\" data-id=\"97e83ed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e00ff9e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e00ff9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P13.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"NANO-FortiEGG: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21 DHA \u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e17\u0e22\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P13.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tNANO-FortiEGG: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21 DHA \u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e17\u0e22\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c6e0410\" data-id=\"c6e0410\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d98551 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"6d98551\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P14.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"eLysozyme-T1 n+: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e44\u0e02\u0e48\u0e02\u0e32\u0e27 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P14.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\teLysozyme-T1 n+: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e44\u0e02\u0e48\u0e02\u0e32\u0e27 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a05aeb\" data-id=\"6a05aeb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae37966 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ae37966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P15.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e25\u0e34\u0e48\u0e19\u0e23\u0e2a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P15.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e25\u0e34\u0e48\u0e19\u0e23\u0e2a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6683414 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6683414\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5628515\" data-id=\"5628515\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8923bd elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"f8923bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P16.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e32\u0e01\u0e0a\u0e32\u0e19\u0e2d\u0e49\u0e2d\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e39\u0e23\u0e39\u0e1e\u0e23\u0e38\u0e19\u0e2a\u0e39\u0e07\u0e14\u0e39\u0e14\u0e0b\u0e31\u0e1a\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P16.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e32\u0e01\u0e0a\u0e32\u0e19\u0e2d\u0e49\u0e2d\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e39\u0e23\u0e39\u0e1e\u0e23\u0e38\u0e19\u0e2a\u0e39\u0e07\u0e14\u0e39\u0e14\u0e0b\u0e31\u0e1a\u0e01\u0e25\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-99bab00\" data-id=\"99bab00\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c7af40 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3c7af40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P23.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"PhytoEX \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e22\u0e38\u0e22\u0e37\u0e19\u0e22\u0e32\u0e27\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P23.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tPhytoEX \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e22\u0e38\u0e22\u0e37\u0e19\u0e22\u0e32\u0e27\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a977aa8\" data-id=\"a977aa8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43215c2 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"43215c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P05.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e04\u0e17\u0e35\u0e23\u0e35\u0e42\u0e2d\u0e1f\u0e32\u0e08\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e01\u0e38\u0e49\u0e07\u0e17\u0e30\u0e40\u0e25\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P05.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e04\u0e17\u0e35\u0e23\u0e35\u0e42\u0e2d\u0e1f\u0e32\u0e08\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e43\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e01\u0e38\u0e49\u0e07\u0e17\u0e30\u0e40\u0e25\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bde5896 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bde5896\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0f7e5e\" data-id=\"f0f7e5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd7c26e elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"dd7c26e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e01\u0e29\u0e15\u0e23 (Bioindustry and Agricultural Value Addition)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b66198d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b66198d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a92b348 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a92b348\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-40ffe3a\" data-id=\"40ffe3a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebaa574 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ebaa574\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P17.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e25\u0e34\u0e01\u0e19\u0e34\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P17.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e25\u0e34\u0e01\u0e19\u0e34\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-11cea0f\" data-id=\"11cea0f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc1a48c elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"bc1a48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P18.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"TreFast: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e23\u0e35\u0e2e\u0e32\u0e42\u0e25\u0e2a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P18.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tTreFast: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e23\u0e35\u0e2e\u0e32\u0e42\u0e25\u0e2a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c00ef4f\" data-id=\"c00ef4f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aec9c08 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"aec9c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P19.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e23\u0e47\u0e2d\u0e01\u0e0b\u0e34\u0e44\u0e0b\u0e21\u0e4c: \u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e15\u0e49\u0e32\u0e19\u0e2d\u0e19\u0e38\u0e21\u0e39\u0e25\u0e2d\u0e34\u0e2a\u0e23\u0e30\u0e08\u0e32\u0e01\u0e08\u0e38\u0e25\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P19.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e23\u0e47\u0e2d\u0e01\u0e0b\u0e34\u0e44\u0e0b\u0e21\u0e4c: \u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e15\u0e49\u0e32\u0e19\u0e2d\u0e19\u0e38\u0e21\u0e39\u0e25\u0e2d\u0e34\u0e2a\u0e23\u0e30\u0e08\u0e32\u0e01\u0e08\u0e38\u0e25\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d0dd1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d0dd1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-30ea3e7\" data-id=\"30ea3e7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1e6506 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b1e6506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P20.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u0e0b\u0e34\u0e25\u0e04\u0e4c\u0e42\u0e1b\u0e23: \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e25\u0e2d\u0e01\u0e01\u0e32\u0e27\u0e44\u0e2b\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P20.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\t\u0e0b\u0e34\u0e25\u0e04\u0e4c\u0e42\u0e1b\u0e23: \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e25\u0e2d\u0e01\u0e01\u0e32\u0e27\u0e44\u0e2b\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c839d83\" data-id=\"c839d83\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33de9a2 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"33de9a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P21.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"CottonPro: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e08\u0e32\u0e01\u0e08\u0e38\u0e25\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e25\u0e35\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e15\u0e48\u0e33\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P21.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tCottonPro: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e08\u0e32\u0e01\u0e08\u0e38\u0e25\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e25\u0e35\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e15\u0e48\u0e33\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ce720e9\" data-id=\"ce720e9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0818b0 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"c0818b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P22.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Rettizyme: \u0e21\u0e31\u0e25\u0e15\u0e34\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e39\u0e48\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e08\u0e32\u0e01\u0e43\u0e1a\u0e2a\u0e31\u0e1b\u0e1b\u0e30\u0e23\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2a\u0e39\u0e07\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/showcase-for-ministers\/NSTDA-MOAC-G1-P22.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tRettizyme: \u0e21\u0e31\u0e25\u0e15\u0e34\u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e39\u0e48\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e08\u0e32\u0e01\u0e43\u0e1a\u0e2a\u0e31\u0e1b\u0e1b\u0e30\u0e23\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2a\u0e39\u0e07\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e63f680 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e63f680\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c19d625\" data-id=\"c19d625\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2afcdd6 animated-fast elementor-invisible elementor-widget elementor-widget-button\" data-id=\"2afcdd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e37\u0e0a\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 (Precision Agriculture and Sustainable Crop Production) \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 1: \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e44\u0e17\u0e22 \u0e1c\u0e2a\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07\u0e27\u0e31\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 1 \u0e41\u0e25\u0e30\u0e16\u0e31\u0e48\u0e27\u0e1d\u0e31\u0e01\u0e22\u0e32\u0e27 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22 (\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01) \u201cNANO nCote (\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e04\u0e15)\u201d Controlled Release Fertilizer: CRF ChelaPlant-Nano \u0e1b\u0e38\u0e4b\u0e22\u0e19\u0e32\u0e42\u0e19\u0e04\u0e35\u0e40\u0e25\u0e15\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e08\u0e32\u0e01\u0e2d\u0e19\u0e38\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 (Food, Health, and Functional Ingredients Innovation) \u0e01\u0e32\u0e41\u0e1f\u0e2b\u0e21\u0e31\u0e01: \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e1c\u0e07\u0e2b\u0e21\u0e31\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c : \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e42\u0e04\u0e08\u0e34\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e41\u0e25\u0e04\u0e42\u0e15\u0e41\u0e04\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c : \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e42\u0e1e\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 : \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e02\u0e19\u0e32\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 Green Rice Biome: \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21\u0e21\u0e30\u0e25\u0e34\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2142,"parent":83899,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/executive_v3.php","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"footnotes":""},"class_list":["post-84252","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c - NSTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c - NSTDA\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e37\u0e0a\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 (Precision Agriculture and Sustainable Crop Production) \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 1: \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e44\u0e17\u0e22 \u0e1c\u0e2a\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07\u0e27\u0e31\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 1 \u0e41\u0e25\u0e30\u0e16\u0e31\u0e48\u0e27\u0e1d\u0e31\u0e01\u0e22\u0e32\u0e27 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22 (\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01) \u201cNANO nCote (\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e04\u0e15)\u201d Controlled Release Fertilizer: CRF ChelaPlant-Nano \u0e1b\u0e38\u0e4b\u0e22\u0e19\u0e32\u0e42\u0e19\u0e04\u0e35\u0e40\u0e25\u0e15\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e08\u0e32\u0e01\u0e2d\u0e19\u0e38\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 (Food, Health, and Functional Ingredients Innovation) \u0e01\u0e32\u0e41\u0e1f\u0e2b\u0e21\u0e31\u0e01: \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e1c\u0e07\u0e2b\u0e21\u0e31\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c : \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e42\u0e04\u0e08\u0e34\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e41\u0e25\u0e04\u0e42\u0e15\u0e41\u0e04\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c : \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e42\u0e1e\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 : \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e02\u0e19\u0e32\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 Green Rice Biome: \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21\u0e21\u0e30\u0e25\u0e34\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T08:12:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/09\/images-default.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/\",\"name\":\"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/images-default.jpg\",\"datePublished\":\"2026-05-13T10:01:21+00:00\",\"dateModified\":\"2026-05-14T08:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/images-default.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/images-default.jpg\",\"width\":585,\"height\":390},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/moac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NSTDA: The National Research Engine \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e15\u0e34\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/nstda-showcase-for-ministers-2026\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c - NSTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/","og_locale":"en_US","og_type":"article","og_title":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c - NSTDA","og_description":"\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e37\u0e0a\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 (Precision Agriculture and Sustainable Crop Production) \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 1: \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e44\u0e17\u0e22 \u0e1c\u0e2a\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07\u0e27\u0e31\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 1 \u0e41\u0e25\u0e30\u0e16\u0e31\u0e48\u0e27\u0e1d\u0e31\u0e01\u0e22\u0e32\u0e27 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e38\u0e4b\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22 (\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01) \u201cNANO nCote (\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e04\u0e15)\u201d Controlled Release Fertilizer: CRF ChelaPlant-Nano \u0e1b\u0e38\u0e4b\u0e22\u0e19\u0e32\u0e42\u0e19\u0e04\u0e35\u0e40\u0e25\u0e15\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e08\u0e32\u0e01\u0e2d\u0e19\u0e38\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 (Food, Health, and Functional Ingredients Innovation) \u0e01\u0e32\u0e41\u0e1f\u0e2b\u0e21\u0e31\u0e01: \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e1c\u0e07\u0e2b\u0e21\u0e31\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c : \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e42\u0e04\u0e08\u0e34\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e41\u0e25\u0e04\u0e42\u0e15\u0e41\u0e04\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c : \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e42\u0e1e\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 : \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e02\u0e19\u0e32\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e36\u0e48\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 Green Rice Biome: \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21\u0e21\u0e30\u0e25\u0e34\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2026-05-14T08:12:11+00:00","og_image":[{"width":585,"height":390,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/09\/images-default.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/","url":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/","name":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/09\/images-default.jpg","datePublished":"2026-05-13T10:01:21+00:00","dateModified":"2026-05-14T08:12:11+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/09\/images-default.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/09\/images-default.jpg","width":585,"height":390},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/moac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"NSTDA: The National Research Engine \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e15\u0e34","item":"https:\/\/www.nstda.or.th\/home\/nstda-showcase-for-ministers-2026\/"},{"@type":"ListItem","position":3,"name":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/pages\/84252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/comments?post=84252"}],"version-history":[{"count":30,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/pages\/84252\/revisions"}],"predecessor-version":[{"id":84673,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/pages\/84252\/revisions\/84673"}],"up":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/pages\/83899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/2142"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=84252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}