{"id":6409,"date":"2020-07-10T08:43:15","date_gmt":"2020-07-10T01:43:15","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/2020\/07\/10\/20200710-bcg\/"},"modified":"2021-02-13T17:47:55","modified_gmt":"2021-02-13T10:47:55","slug":"20200710-bcg","status":"publish","type":"news_post","link":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/","title":{"rendered":"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19"},"content":{"rendered":"<p>\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e42\u0e14\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e1b.\u0e2d\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e01\u0e2a\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e2d\u0e27\u0e0a.) \u0e41\u0e25\u0e30 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) <strong>\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08 \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u201c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e21\u0e31\u0e0a\u0e0a\u0e32 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u201d<\/strong> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 <strong>\u0e43\u0e19\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 15 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32 8.00 \u2013 16.00 \u0e19. \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35<\/strong> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (Live) \u0e44\u0e14\u0e49\u0e17\u0e32\u0e07 <a href=\"https:\/\/www.facebook.com\/NSTDATHAILAND\/\">Facebook NSTDA-\u0e2a\u0e27\u0e17\u0e0a. (\u0e04\u0e25\u0e34\u0e01)<\/a><\/p>\n<p><img decoding=\"async\" class=\" size-full wp-image-969\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/07\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01.jpg\" width=\"800\" \/><b><\/b><\/p>\n<p><!--more--><\/p>\n<p><b>\u0e44\u0e1f\u0e25\u0e4c\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d 9 \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u00a0https:\/\/drive.google.com\/drive\/folders\/1Dujeq-81IU_Zw9FK-yd3P8FtBjvA3FqH?usp=sharin<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-01Agriculture.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-02Food.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e2d\u0e32\u0e2b\u0e32\u0e23<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-03Energy.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-04Innovation.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e39\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2a\u0e39\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-05Vaccine.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e22\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-06Medical.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-07Travel.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-08CircularEconomy.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19<\/a><\/li>\n<li><a href=\"https:\/\/waa.inter.nstda.or.th\/stks\/pub\/2020\/20200715-09CreativeEconomy-Final.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u00a0<\/a><\/li>\n<\/ul>\n<p><b>\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e32\u0e23<\/b><b><br \/>\n<\/b><b>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e21\u0e31\u0e0a\u0e0a\u0e32 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/b><b><br \/>\n<\/b><b>\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 15 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21\u00a0 2563\u00a0 \u0e40\u0e27\u0e25\u0e32 08.00 &#8211; 16.00 \u0e19.<\/b><b><br \/>\n<\/b><b>\u0e13 \u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e47\u0e04\u0e1f\u0e2d\u0e23\u0e31\u0e48\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e2d\u0e25\u0e23\u0e39\u0e21<\/b><b><br \/>\n<\/b><b>\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e47\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35<\/b><\/p>\n<p>08.00 &#8211; 08.30 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19<br \/>\n08.30 &#8211; 09.00 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e27\u0e34\u0e14\u0e35\u0e17\u0e31\u0e28\u0e19\u0e4c<br \/>\n09.00 &#8211; 09.05 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e38\u0e1b\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e21\u0e31\u0e0a\u0e0a\u0e32 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<br \/>\n\u0e42\u0e14\u0e22 <strong>\u0e14\u0e23.\u0e2a\u0e38\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e21\u0e29\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u00a0 <\/strong><br \/>\n<strong> \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.)<\/strong><br \/>\n09.05 &#8211; 09.15 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e1e\u0e34\u0e18\u0e35\u0e25\u0e07\u0e19\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27<br \/>\n(BCG \u0e42\u0e21\u0e40\u0e14\u0e25) \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<br \/>\n\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e01\u0e02\u0e35\u0e1e\u0e22\u0e32\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07 \u0e2d\u0e27.<br \/>\n09.15 &#8211; 09.20 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e2b\u0e21\u0e39\u0e48<br \/>\n09.20 &#8211; 09.50 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e1b\u0e32\u0e10\u0e01\u0e16\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07<br \/>\n\u201cBCG: \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u201d<br \/>\n\u0e42\u0e14\u0e22 <strong>\u0e1e\u0e25\u0e40\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e17\u0e18\u0e4c\u00a0 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e42\u0e2d\u0e0a\u0e32 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35<\/strong><br \/>\n09.50 &#8211; 10.00 \u0e19.\u00a0\u00a0\u00a0\u00a0 \u0e19\u0e33\u0e0a\u0e21\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e42\u0e0a\u0e27\u0e4c\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 BCG<br \/>\n\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<br \/>\n\u0e42\u0e14\u0e22 <strong>\u0e14\u0e23.\u0e2a\u0e38\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e21\u0e29\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u00a0 <\/strong><br \/>\n<strong> \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.)<\/strong><br \/>\n10.30 &#8211; 12.00 \u0e19.\u00a0\u00a0\u00a0\u00a0 9 \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34<br \/>\n1. \u0e19\u0e32\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e22\u0e38\u0e04\u0e25 \u0e25\u0e34\u0e49\u0e21\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07 : \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23<br \/>\n2. \u0e19\u0e32\u0e22\u0e18\u0e35\u0e23\u0e1e\u0e07\u0e28\u0e4c \u0e08\u0e31\u0e19\u0e28\u0e34\u0e23\u0e34 : \u0e2d\u0e32\u0e2b\u0e32\u0e23<br \/>\n3. \u0e19\u0e32\u0e22\u0e40\u0e17\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19\u0e34\u0e0a : \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e<br \/>\n4. \u0e19\u0e32\u0e22\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e27\u0e48\u0e2d\u0e07\u0e01\u0e38\u0e28\u0e25\u0e01\u0e34\u0e08 : \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e39\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2a\u0e39\u0e07\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<br \/>\n5. \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13 \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1b\u0e34\u0e22\u0e30\u0e2a\u0e01\u0e25 \u0e2a\u0e01\u0e25\u0e2a\u0e31\u0e15\u0e22\u0e32\u0e17\u0e23 : \u0e22\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19<br \/>\n6. \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e44\u0e1e\u0e23\u0e31\u0e0a \u0e18\u0e31\u0e0a\u0e22\u0e1e\u0e07\u0e29\u0e4c : \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c<br \/>\n7. \u0e19\u0e32\u0e22\u0e01\u0e25\u0e34\u0e19\u0e17\u0e4c \u0e2a\u0e32\u0e23\u0e2a\u0e34\u0e19 : \u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27<br \/>\n8. \u0e14\u0e23.\u0e27\u0e34\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e2a\u0e34\u0e21\u0e32\u0e09\u0e32\u0e22\u0e32 : \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19<br \/>\n9. \u0e19\u0e32\u0e22\u0e27\u0e35\u0e23\u0e30\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e42\u0e04\u0e27\u0e2a\u0e38\u0e23\u0e31\u0e15\u0e19\u0e4c : \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c<br \/>\n\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e28\u0e34\u0e23\u0e34\u0e40\u0e25\u0e34\u0e28\u0e27\u0e23\u0e01\u0e38\u0e25 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a.<\/p>\n<p>13.00 &#8211; 16.00 \u0e19\u00a0\u00a0\u00a0\u00a0 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e30\u0e14\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e22\u0e48\u0e2d\u0e22 8 \u0e01\u0e25\u0e38\u0e48\u0e21<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 1\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 (\u0e2b\u0e49\u0e2d\u0e07 101-102)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 :\u00a0 \u0e19\u0e32\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e22\u0e38\u0e04\u0e25\u00a0 \u0e25\u0e34\u0e49\u0e21\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 2\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23 (\u0e2b\u0e49\u0e2d\u0e07 103-104)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 : \u0e19\u0e32\u0e22\u0e18\u0e35\u0e23\u0e1e\u0e07\u0e28\u0e4c\u00a0 \u0e08\u0e31\u0e19\u0e28\u0e34\u0e23\u0e34<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 3\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e (\u0e2b\u0e49\u0e2d\u0e07 111-112)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 :\u00a0 \u0e19\u0e32\u0e22\u0e40\u0e17\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c\u00a0 \u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19\u0e34\u0e0a<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 4\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 (\u0e2b\u0e49\u0e2d\u0e07 204)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 :<br \/>\n\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13 \u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1b\u0e34\u0e22\u0e30\u0e2a\u0e01\u0e25 \u0e2a\u0e01\u0e25\u0e2a\u0e31\u0e15\u0e22\u0e32\u0e17\u0e23<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 5\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c (\u0e2b\u0e49\u0e2d\u0e07 205)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 : \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e44\u0e1e\u0e23\u0e31\u0e0a \u0e18\u0e31\u0e0a\u0e22\u0e1e\u0e07\u0e29\u0e4c<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 6\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u00a0 (\u0e2b\u0e49\u0e2d\u0e07\u00a0 206)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 : \u0e19\u0e32\u0e22\u0e01\u0e25\u0e34\u0e19\u0e17\u0e4c\u00a0 \u0e2a\u0e32\u0e23\u0e2a\u0e34\u0e19<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 7\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 (\u0e2b\u0e49\u0e2d\u0e07 108-109)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 : \u0e14\u0e23.\u0e27\u0e34\u0e08\u0e32\u0e23\u0e22\u0e4c\u00a0 \u0e2a\u0e34\u0e21\u0e32\u0e09\u0e32\u0e22\u0e32<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48 8\u00a0 BCG-\u0e2a\u0e32\u0e02\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u00a0 (\u0e2b\u0e49\u0e2d\u0e07 203)<br \/>\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 : \u0e19\u0e32\u0e22\u0e27\u0e35\u0e23\u0e30\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u00a0 \u0e42\u0e04\u0e27\u0e2a\u0e38\u0e23\u0e31\u0e15\u0e19\u0e4c<\/p>\n<p><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2FNSTDATHAILAND%2Fvideos%2F1187094418290973%2F&amp;show_text=false&amp;width=735&amp;appId=130436997021390&amp;height=412\" width=\"735\" height=\"412\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2FNSTDATHAILAND%2Fvideos%2F1195734240762674%2F&amp;show_text=false&amp;width=735&amp;appId=130436997021390&amp;height=412\" width=\"735\" height=\"412\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"author":3,"featured_media":9754,"template":"","categories":[1077,253],"tags":[899],"class_list":["post-6409","news_post","type-news_post","status-publish","has-post-thumbnail","hentry","category-bcg-cat","category-pr-cat","tag-bcg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 - NSTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 - NSTDA\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e42\u0e14\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e1b.\u0e2d\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e01\u0e2a\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e2d\u0e27\u0e0a.) \u0e41\u0e25\u0e30 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08 \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u201c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e21\u0e31\u0e0a\u0e0a\u0e32 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 15 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32 8.00 \u2013 16.00 \u0e19. \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (Live) \u0e44\u0e14\u0e49\u0e17\u0e32\u0e07 Facebook NSTDA-\u0e2a\u0e27\u0e17\u0e0a. (\u0e04\u0e25\u0e34\u0e01)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-13T10:47:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/07\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/\",\"name\":\"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg\",\"datePublished\":\"2020-07-10T01:43:15+00:00\",\"dateModified\":\"2021-02-13T10:47:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/20200710-bcg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 - NSTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/","og_locale":"en_US","og_type":"article","og_title":"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 - NSTDA","og_description":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e42\u0e14\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e1b.\u0e2d\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e01\u0e2a\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e2d\u0e27\u0e0a.) \u0e41\u0e25\u0e30 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08 \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u201c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e21\u0e31\u0e0a\u0e0a\u0e32 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 15 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2563 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32 8.00 \u2013 16.00 \u0e19. \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e34\u0e21\u0e41\u0e1e\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (Live) \u0e44\u0e14\u0e49\u0e17\u0e32\u0e07 Facebook NSTDA-\u0e2a\u0e27\u0e17\u0e0a. (\u0e04\u0e25\u0e34\u0e01)","og_url":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2021-02-13T10:47:55+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/07\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/","url":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/","name":"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/07\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg","datePublished":"2020-07-10T01:43:15+00:00","dateModified":"2021-02-13T10:47:55+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/07\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2020\/07\/images_News-PR_2020_072020_Banner_NSTDA-BCG-live_1920x1080_pixel-01-1-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/20200710-bcg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27","item":"https:\/\/www.nstda.or.th\/home\/news_post\/"},{"@type":"ListItem","position":3,"name":"\u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e1b.\u0e2d\u0e27. \u0e2a\u0e01\u0e2a\u0e27. \u0e2a\u0e2d\u0e27\u0e0a. \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e17\u0e0a. \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG : \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/6409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/news_post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/6409\/revisions"}],"predecessor-version":[{"id":13267,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/6409\/revisions\/13267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/9754"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=6409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/categories?post=6409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/tags?post=6409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}