{"id":48331,"date":"2023-10-20T13:28:53","date_gmt":"2023-10-20T06:28:53","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/?post_type=news_post&#038;p=48331"},"modified":"2023-10-20T19:40:47","modified_gmt":"2023-10-20T12:40:47","slug":"pr-nstda-20102566","status":"publish","type":"news_post","link":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/","title":{"rendered":"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019"},"content":{"rendered":"<p><strong>(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 <\/strong><strong>20 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2566)<\/strong> \u0e13 \u0e2a\u0e31\u0e1b\u0e1b\u0e32\u0e22\u0e30\u0e2a\u0e20\u0e32\u0e2a\u0e16\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32(\u0e1d\u0e31\u0e48\u0e07\u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32) : \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e19\u0e33\u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e40\u0e08\u0e19\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e04\u0e13\u0e32\u0e18\u0e32\u0e23\u0e13\u0e32 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e27\u0e34\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e44\u0e0a\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19<strong>\u0e1e\u0e34\u0e18\u0e35\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48<\/strong> \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32 (Economy Under the Forest)\u201d<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-48336\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1620\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-300x190.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-1024x648.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-768x486.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-1536x972.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7207-2048x1296.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>\u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e0a\u0e38\u0e15\u0e34\u0e40\u0e14\u0e0a \u0e21\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22 \u0e2d\u0e08\u0e25\u0e1a\u0e38\u0e0d \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e20\u0e32\u0e27\u0e34\u0e13\u0e35 \u0e2a\u0e31\u0e15\u0e22\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e27\u0e31\u0e18 \u0e27\u0e07\u0e28\u0e4c\u0e27\u0e23\u0e23\u0e13 \u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b \u0e1a\u0e34\u0e19\u0e0a\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 \u0e1e\u0e19\u0e21\u0e02\u0e27\u0e31\u0e0d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e19\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e25\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e08\u0e34\u0e19 \u0e08\u0e31\u0e48\u0e19\u0e15\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2d\u0e20\u0e34\u0e0a\u0e32\u0e15\u0e34 \u0e42\u0e15\u0e14\u0e34\u0e25\u0e01\u0e40\u0e27\u0e0a\u0e0a\u0e4c \u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e01\u0e02\u0e35\u0e1e\u0e22\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-48334\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7178-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<td style=\"width: 50%;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-48338\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7196-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u0e19\u0e32\u0e22\u0e2d\u0e20\u0e34\u0e0a\u0e32\u0e15\u0e34 \u0e42\u0e15\u0e14\u0e34\u0e25\u0e01\u0e40\u0e27\u0e0a\u0e0a\u0e4c \u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48 \u0e44\u0e14\u0e49\u0e25\u0e07\u0e19\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32 (Economy Under the Forest)\u201d (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 7 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2566) \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e15\u0e33\u0e1a\u0e25\u0e43\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e34\u0e40\u0e23\u0e34\u0e48\u0e21\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e42\u0e14\u0e22\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e1c\u0e25\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e44\u0e14\u0e49\u0e40\u0e25\u0e47\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e40\u0e0a\u0e34\u0e0d\u0e43\u0e2b\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u00a0\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07 \u0e2a\u0e27\u0e17\u0e0a. \u0e21\u0e35\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e16\u0e36\u0e07 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e44\u0e01\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32 (Economy Under the Forest)\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e09\u0e1a\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21 7 \u0e1d\u0e48\u0e32\u0e22 \u0e04\u0e37\u0e2d \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1e\u0e23\u0e48 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48339\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7197-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48340\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7188-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u201c\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e35\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e2a\u0e27\u0e17\u0e0a. \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1.\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e31\u0e01\u0e29\u0e30 (re-skill\/up-skill) \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e48\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e48\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 2.\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e49\u0e0a\u0e38\u0e21\u0e0a\u0e19 3. \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30 4. \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e0b\u0e31\u0e1a\u0e01\u0e4a\u0e32\u0e0b\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 (\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e25\u0e1e\u0e34\u0e29\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e32\u0e1b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e04\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48\u201d<em> \u00a0<\/em><strong>\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f<\/strong> \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48332\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7183-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48337\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7198-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u0e14\u0e23.\u0e40\u0e08\u0e19\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e04\u0e13\u0e32\u0e18\u0e32\u0e23\u0e13\u0e32<\/strong> <strong>\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a.<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e14\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e40\u0e25\u0e47\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32 (Economy Under the Forest)\u201d \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e2a\u0e27\u0e17\u0e0a. \u0e42\u0e14\u0e22 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23 (\u0e2a\u0e17.) \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e33\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21(\u0e27\u0e17\u0e19.) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19 \u0e27\u0e17\u0e19. \u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e1a\u0e27\u0e01\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 <strong>\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08<\/strong> \u0e04\u0e37\u0e2d \u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e0a\u0e35\u0e1e <strong>\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21<\/strong> \u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1e\u0e22\u0e1e\u0e22\u0e49\u0e32\u0e22\u0e16\u0e34\u0e48\u0e19 \u0e40\u0e01\u0e34\u0e14\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30<strong>\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21<\/strong> \u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e25\u0e14\u0e01\u0e32\u0e23\u0e17\u0e33\u0e25\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG (Bio-Circular-Green Economy Model) \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e21\u0e40\u0e14\u0e25\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e23\u0e27\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 3 \u0e21\u0e34\u0e15\u0e34 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e41\u0e25\u0e30\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 SDGs \u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e2b\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48335\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1683\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-300x197.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-1024x673.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-768x505.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-1536x1010.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7283-2048x1346.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-48333\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-scaled.jpg 2560w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-1024x684.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-768x513.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-1536x1025.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/DSC_7306-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u0e14\u0e49\u0e32\u0e19<strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e27\u0e34\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e44\u0e0a\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c<\/strong> <strong>\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a.<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e27\u0e48\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e2f \u0e19\u0e35\u0e49 \u0e2a\u0e27\u0e17\u0e0a. \u0e42\u0e14\u0e22 \u0e2a\u0e17.\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19 4 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 <strong>1.\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e <\/strong>\u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a \u0e1e\u0e37\u0e0a\u0e1b\u0e48\u0e32 \u0e1e\u0e37\u0e0a\u0e2b\u0e32\u0e22\u0e32\u0e01 \u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e25\u0e31\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e14\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1b\u0e48\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 <strong>2.\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19<\/strong> \u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e1c\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e48\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e2b\u0e47\u0e14\u0e1b\u0e48\u0e32\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e0a\u0e31\u0e19\u0e42\u0e23\u0e07 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e04\u0e23\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2e\u0e48\u0e2d\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e35\u0e22\u0e49\u0e2d\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 <strong>3.\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48<\/strong> \u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Smart IoT \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e33\u0e43\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e1e\u0e32\u0e30\u0e0a\u0e33\u0e01\u0e25\u0e49\u0e32\u0e44\u0e21\u0e49 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 PM2.5 \u0e41\u0e25\u0e30\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e44\u0e1f\u0e1b\u0e48\u0e32\u0e43\u0e19\u0e1b\u0e48\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 (\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1d\u0e38\u0e48\u0e19-Nano Sampler) \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e37\u0e0a (\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2a\u0e39\u0e07) \u0e41\u0e25\u0e30 <strong>4.\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27<\/strong> \u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e19\u0e27\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e19\u0e34\u0e40\u0e27\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n","protected":false},"author":16,"featured_media":48341,"template":"","categories":[253],"tags":[],"class_list":["post-48331","news_post","type-news_post","status-publish","has-post-thumbnail","hentry","category-pr-cat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019 - NSTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019 - NSTDA\" \/>\n<meta property=\"og:description\" content=\"(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2566) \u0e13 \u0e2a\u0e31\u0e1b\u0e1b\u0e32\u0e22\u0e30\u0e2a\u0e20\u0e32\u0e2a\u0e16\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32(\u0e1d\u0e31\u0e48\u0e07\u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32) : \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e19\u0e33\u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e40\u0e08\u0e19\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e04\u0e13\u0e32\u0e18\u0e32\u0e23\u0e13\u0e32 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e27\u0e34\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e44\u0e0a\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32 (Economy Under the Forest)\u201d \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e0a\u0e38\u0e15\u0e34\u0e40\u0e14\u0e0a \u0e21\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22 \u0e2d\u0e08\u0e25\u0e1a\u0e38\u0e0d \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e20\u0e32\u0e27\u0e34\u0e13\u0e35 \u0e2a\u0e31\u0e15\u0e22\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e27\u0e31\u0e18 \u0e27\u0e07\u0e28\u0e4c\u0e27\u0e23\u0e23\u0e13 \u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b \u0e1a\u0e34\u0e19\u0e0a\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 \u0e1e\u0e19\u0e21\u0e02\u0e27\u0e31\u0e0d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e19\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e25\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e08\u0e34\u0e19 \u0e08\u0e31\u0e48\u0e19\u0e15\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T12:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/New-Project11-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/\",\"name\":\"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019 - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/New-Project11-13.jpg\",\"datePublished\":\"2023-10-20T06:28:53+00:00\",\"dateModified\":\"2023-10-20T12:40:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/New-Project11-13.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/New-Project11-13.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-20102566\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019 - NSTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/","og_locale":"en_US","og_type":"article","og_title":"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019 - NSTDA","og_description":"(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2566) \u0e13 \u0e2a\u0e31\u0e1b\u0e1b\u0e32\u0e22\u0e30\u0e2a\u0e20\u0e32\u0e2a\u0e16\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e31\u0e10\u0e2a\u0e20\u0e32(\u0e1d\u0e31\u0e48\u0e07\u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32) : \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e19\u0e33\u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e40\u0e08\u0e19\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e04\u0e13\u0e32\u0e18\u0e32\u0e23\u0e13\u0e32 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e27\u0e34\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e44\u0e0a\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u201c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32 (Economy Under the Forest)\u201d \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e0a\u0e38\u0e15\u0e34\u0e40\u0e14\u0e0a \u0e21\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22 \u0e2d\u0e08\u0e25\u0e1a\u0e38\u0e0d \u0e2d\u0e18\u0e34\u0e1a\u0e14\u0e35\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e38\u0e20\u0e32\u0e27\u0e34\u0e13\u0e35 \u0e2a\u0e31\u0e15\u0e22\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e27\u0e31\u0e18 \u0e27\u0e07\u0e28\u0e4c\u0e27\u0e23\u0e23\u0e13 \u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e17\u0e35\u0e1b \u0e1a\u0e34\u0e19\u0e0a\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1e\u0e23\u0e48 \u0e19\u0e32\u0e22\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 \u0e1e\u0e19\u0e21\u0e02\u0e27\u0e31\u0e0d \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e48 \u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e19\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e25\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e08\u0e34\u0e19 \u0e08\u0e31\u0e48\u0e19\u0e15\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2023-10-20T12:40:47+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/New-Project11-13.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/","url":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/","name":"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019 - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/New-Project11-13.jpg","datePublished":"2023-10-20T06:28:53+00:00","dateModified":"2023-10-20T12:40:47+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/New-Project11-13.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/10\/New-Project11-13.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-20102566\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27","item":"https:\/\/www.nstda.or.th\/home\/news_post\/"},{"@type":"ListItem","position":3,"name":"\u0e01\u0e21\u0e18.\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e27\u0e38\u0e12\u0e34\u0e2a\u0e20\u0e32 \u0e14\u0e36\u0e07 6 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1c\u0e19\u0e36\u0e01 \u0e2a\u0e27\u0e17\u0e0a.\u00a0 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35-\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u2018\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e1b\u0e48\u0e32\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u2019"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/48331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/news_post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":2,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/48331\/revisions"}],"predecessor-version":[{"id":48353,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/48331\/revisions\/48353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/48341"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=48331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/categories?post=48331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/tags?post=48331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}