{"id":46834,"date":"2023-09-11T00:08:28","date_gmt":"2023-09-10T17:08:28","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/?post_type=news_post&#038;p=46834"},"modified":"2023-09-11T19:50:09","modified_gmt":"2023-09-11T12:50:09","slug":"pr-nstda-robo-innovator-challenge-2023","status":"publish","type":"news_post","link":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/","title":{"rendered":"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f"},"content":{"rendered":"<p>(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566) \u0e13 \u0e25\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e0a\u0e31\u0e49\u0e19 2 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e23\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15: \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22 \u0e40\u0e02\u0e15\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Software Park Thailand: SWP) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (PTEC) \u0e41\u0e25\u0e30 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c SQUAT \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e40\u0e19\u0e04\u0e40\u0e17\u0e04) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (\u0e01\u0e17\u0e1b\u0e2a.)<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-46837\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02485-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p>\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u201cRobo Innovator Challenge 2023 By Software Park Thailand\u201d \u0e0a\u0e34\u0e07\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32 \u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1f\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e40\u0e28\u0e29 (Talent) \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (Self-Driving Car) \u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-46838\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02496-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><strong>\u0e14\u0e23.\u0e20\u0e31\u0e17\u0e23\u0e32\u0e27\u0e14\u0e35 \u0e1e\u0e25\u0e2d\u0e22\u0e01\u0e34\u0e15\u0e34\u0e01\u0e39\u0e25 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e02\u0e15\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04) \u0e2a\u0e27\u0e17\u0e0a. <\/strong>\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2563 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e38\u0e01\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e2b\u0e23\u0e37\u0e2d Artificial Intelligent (AI) \u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e49\u0e32\u0e27\u0e02\u0e49\u0e32\u0e21\u0e01\u0e0e\u0e41\u0e25\u0e30\u0e01\u0e15\u0e34\u0e01\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e46 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e49\u0e32\u0e27\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e21\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e19\u0e33\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p>\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e08\u0e39\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c (Junior) \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e15\u0e32\u0e21\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e21\u0e40\u0e08\u0e2d\u0e23\u0e4c (Major) \u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e33\u0e25\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\n<p>\u201c\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01 \u0e2a\u0e27\u0e17\u0e0a. \u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e38\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u201d<\/p>\n<p><strong>\u0e14\u0e23.\u0e20\u0e31\u0e17\u0e23\u0e32\u0e27\u0e14\u0e35<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e23\u0e34\u0e22\u0e30 Robo Innovator Challenge 2023 By Software Park Thailand \u0e0a\u0e34\u0e07\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32 \u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e31\u0e14\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 8-10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566 \u0e44\u0e14\u0e49\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e38\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e48\u0e27\u0e21\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e38\u0e01\u0e17\u0e35\u0e21 \u0e02\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e25\u0e30\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e17\u0e48\u0e32\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e25\u0e49\u0e33\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e43\u0e19\u0e40\u0e27\u0e17\u0e35\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e37\u0e1a\u0e44\u0e1b<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-46836\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02478-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><strong>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 <\/strong><strong>Junior \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e2d\u0e32\u0e22\u0e38 13-18 \u0e1b\u0e35 \u0e1c\u0e25\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e27\u0e48\u0e32 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e21Robot A <\/strong>\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32\u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 10,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e2d\u0e35\u0e01 1 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u00a0\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e253,000 \u0e1a\u0e32\u0e17 <strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1<\/strong> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e21 EasyKids-RoboSparkz \u00a0\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 7,000 \u0e1a\u0e32\u0e17 <strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2<\/strong> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48\u0e17\u0e35\u0e21\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e32\u0e23\u0e34\u0e19\u0e0a\u0e33\u0e23\u0e32\u0e1a \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 5,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30<strong> \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 <\/strong>\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48\u0e17\u0e35\u0e21 Speedy \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 3,000 \u0e1a\u0e32\u0e17<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46835\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/DSC02427-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><strong>\u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 <\/strong><strong>Major \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e38\u0e48\u0e19\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e0a\u0e48\u0e27\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e1c\u0e25\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e27\u0e48\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e21 FRANNNNN<\/strong> \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32\u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 15,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e2d\u0e35\u0e01 1 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u00a0 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 3,000 \u0e1a\u0e32\u0e17 <strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a <\/strong><strong>1<\/strong> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e21 \u0e40\u0e21\u0e04\u0e04\u0e32\u0e2b\u0e49\u0e2d\u0e07 408 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 10,000 \u0e1a\u0e32\u0e17 <strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a <\/strong><strong>2<\/strong> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e21\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e27\u0e34\u0e48\u0e07\u0e21\u0e31\u0e48\u0e27 \u00a0\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 7,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30 <strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21<\/strong> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e21 EasyKids-Janjam \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 3,000 \u0e1a\u0e32\u0e17<\/p>\n","protected":false},"author":16,"featured_media":46854,"template":"","categories":[253],"tags":[],"class_list":["post-46834","news_post","type-news_post","status-publish","has-post-thumbnail","hentry","category-pr-cat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f - NSTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f - NSTDA\" \/>\n<meta property=\"og:description\" content=\"(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566) \u0e13 \u0e25\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e0a\u0e31\u0e49\u0e19 2 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e23\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15: \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22 \u0e40\u0e02\u0e15\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Software Park Thailand: SWP) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (PTEC) \u0e41\u0e25\u0e30 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c SQUAT \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e40\u0e19\u0e04\u0e40\u0e17\u0e04) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (\u0e01\u0e17\u0e1b\u0e2a.) \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u201cRobo Innovator Challenge 2023 By Software Park Thailand\u201d \u0e0a\u0e34\u0e07\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32 \u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1f\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e40\u0e28\u0e29 (Talent) \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (Self-Driving Car) \u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T12:50:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/New-Project11-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/\",\"name\":\"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/New-Project11-1.jpg\",\"datePublished\":\"2023-09-10T17:08:28+00:00\",\"dateModified\":\"2023-09-11T12:50:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/New-Project11-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/New-Project11-1.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/pr-nstda-robo-innovator-challenge-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f - NSTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/","og_locale":"en_US","og_type":"article","og_title":"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f - NSTDA","og_description":"(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2566) \u0e13 \u0e25\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e0a\u0e31\u0e49\u0e19 2 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e23\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15: \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22 \u0e40\u0e02\u0e15\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Software Park Thailand: SWP) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (PTEC) \u0e41\u0e25\u0e30 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c SQUAT \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e40\u0e19\u0e04\u0e40\u0e17\u0e04) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (\u0e01\u0e17\u0e1b\u0e2a.) \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u201cRobo Innovator Challenge 2023 By Software Park Thailand\u201d \u0e0a\u0e34\u0e07\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e01\u0e19\u0e34\u0e29\u0e10\u0e32\u0e18\u0e34\u0e23\u0e32\u0e0a\u0e40\u0e08\u0e49\u0e32 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e23\u0e32\u0e0a\u0e2a\u0e38\u0e14\u0e32 \u0e2f \u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e21\u0e32\u0e23\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1f\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e34\u0e40\u0e28\u0e29 (Talent) \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (Self-Driving Car) \u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2023-09-11T12:50:09+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/New-Project11-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/","url":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/","name":"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/New-Project11-1.jpg","datePublished":"2023-09-10T17:08:28+00:00","dateModified":"2023-09-11T12:50:09+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/New-Project11-1.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/09\/New-Project11-1.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/pr-nstda-robo-innovator-challenge-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27","item":"https:\/\/www.nstda.or.th\/home\/news_post\/"},{"@type":"ListItem","position":3,"name":"\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u00a0\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e23\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e17\u0e35\u0e21 Robot A \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21 FRANNNNN \u0e04\u0e27\u0e49\u0e32\u0e41\u0e0a\u0e21\u0e1b\u0e4c \u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e17\u0e1e\u0e2f"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/46834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/news_post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":2,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/46834\/revisions"}],"predecessor-version":[{"id":46853,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/46834\/revisions\/46853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/46854"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=46834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/categories?post=46834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/tags?post=46834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}