{"id":40599,"date":"2023-02-17T17:54:56","date_gmt":"2023-02-17T10:54:56","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/?post_type=news_post&#038;p=40599"},"modified":"2023-03-07T15:44:22","modified_gmt":"2023-03-07T08:44:22","slug":"magik-growth-eeci","status":"publish","type":"news_post","link":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/","title":{"rendered":"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21"},"content":{"rendered":"<p>17 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e02\u0e15\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 (EECi): \u0e42\u0e14\u0e22 <strong>\u0e28. \u0e14\u0e23.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e34\u0e21\u0e1b\u0e34\u0e08\u0e33\u0e19\u0e07\u0e04\u0e4c<\/strong> \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.)\u00a0 \u0e19\u0e33\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 Magik Growth\u201d \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-40600\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p>\u0e42\u0e14\u0e22\u0e21\u0e35<strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e08\u0e13\u0e35 \u0e2d\u0e23\u0e23\u0e16\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e20\u0e34\u0e0d\u0e42\u0e0d<\/strong> \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e14\u0e49\u0e32\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e02\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 (\u0e2a\u0e01\u0e1e\u0e2d.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 <strong>\u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e15\u0e4c \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e0a\u0e32\u0e15\u0e34<\/strong> \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19 10,000 \u0e16\u0e38\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2b\u0e48\u0e2d\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-40604\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4323-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><strong>\u0e28. \u0e14\u0e23.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e34\u0e21\u0e1b\u0e34\u0e08\u0e33\u0e19\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a.<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 <strong>\u201c<\/strong>\u0e2a\u0e27\u0e17\u0e0a. \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23 \u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e33\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e38\u0e4b\u0e22 \u0e2b\u0e25\u0e31\u0e01-\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e14\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1b\u0e34\u0e14\u0e1c\u0e19\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e16\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e31\u0e19\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 Magik Growth \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21 \u0e27\u0e48\u0e32\u0e21\u0e35\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e14\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e1c\u0e25\u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e1a\u0e32\u0e07\u0e25\u0e07 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e17\u0e35\u0e48\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 Magik Growth \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 3-5 \u0e1b\u0e35 \u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e35\u0e15\u0e48\u0e2d \u0e46 \u0e44\u0e1b \u0e41\u0e25\u0e30\u0e25\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e44\u0e14\u0e49\u201d<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-40605\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306.jpg\" alt=\"\" width=\"2422\" height=\"1585\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306.jpg 2422w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306-300x196.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306-1024x670.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306-768x503.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306-1536x1005.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4306-2048x1340.jpg 2048w\" sizes=\"(max-width: 2422px) 100vw, 2422px\" \/><\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e02\u0e15\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 EECi \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e42\u0e14\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e42\u0e14\u0e22\u0e23\u0e2d\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e02\u0e2d\u0e07 EECi \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e34\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e42\u0e14\u0e22\u0e23\u0e2d\u0e1a \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e02\u0e2d\u0e07 EECi \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e41\u0e1a\u0e1a STEM (Science, Technology, Engineering and Mathematics) \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e2d\u0e01\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19<\/p>\n<p>\u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e02\u0e2d\u0e07 EECi \u0e2b\u0e23\u0e37\u0e2d EECi RUNs Academy (Re-skill Up-skill New Skill) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e08\u0e32\u0e01\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e33\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40606\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4275-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><strong>\u0e19\u0e32\u0e07\u0e1e\u0e08\u0e13\u0e35 \u0e2d\u0e23\u0e23\u0e16\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e20\u0e34\u0e0d\u0e42\u0e0d \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e14\u0e49\u0e32\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19 <\/strong>\u0e2a\u0e01\u0e1e\u0e2d. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e02\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e2a\u0e27\u0e19\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e21\u0e49\u0e1c\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e19\u0e33\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e08\u0e32\u0e01\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07-\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e0a\u0e32\u0e27\u0e2a\u0e27\u0e19\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15 \u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19<br \/>\n\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40601\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4333-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40603\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4326-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40602\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329.jpg\" alt=\"\" width=\"2500\" height=\"1667\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329.jpg 2500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329-1024x683.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329-1536x1024.jpg 1536w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4329-2048x1366.jpg 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/p>\n<p><strong>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 <\/strong><strong>Magik Growth<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e1b\u0e31\u0e19\u0e1a\u0e2d\u0e19\u0e14\u0e4c\u0e19\u0e2d\u0e19\u0e27\u0e39\u0e40\u0e27\u0e19 (spunbond\u00a0nonwoven) \u0e17\u0e35\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e42\u0e25\u0e2b\u0e30\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e17\u0e04) \u0e2a\u0e27\u0e17\u0e0a. \u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e2a\u0e39\u0e15\u0e23\u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e27\u0e14\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e0a\u0e19\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e21\u0e47\u0e14\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e41\u0e15\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e22\u0e39\u0e27\u0e35 \u0e41\u0e25\u0e30\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 3 \u0e21\u0e34\u0e15\u0e34\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e21\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e23\u0e39\u0e1e\u0e23\u0e38\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e17\u0e35\u0e48\u0e16\u0e48\u0e32\u0e22\u0e40\u0e17\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e47\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49 \u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e2a\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e37\u0e0a\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19 \u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d \u0e16\u0e38\u0e07\u0e1b\u0e25\u0e39\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e25\u0e38\u0e21\u0e14\u0e34\u0e19<\/p>\n","protected":false},"author":16,"featured_media":40600,"template":"","categories":[253],"tags":[],"class_list":["post-40599","news_post","type-news_post","status-publish","has-post-thumbnail","hentry","category-pr-cat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 - NSTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 - NSTDA\" \/>\n<meta property=\"og:description\" content=\"17 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e02\u0e15\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 (EECi): \u0e42\u0e14\u0e22 \u0e28. \u0e14\u0e23.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e34\u0e21\u0e1b\u0e34\u0e08\u0e33\u0e19\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.)\u00a0 \u0e19\u0e33\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 Magik Growth\u201d \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e08\u0e13\u0e35 \u0e2d\u0e23\u0e23\u0e16\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e20\u0e34\u0e0d\u0e42\u0e0d \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e14\u0e49\u0e32\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e02\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 (\u0e2a\u0e01\u0e1e\u0e2d.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e15\u0e4c \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19 10,000 \u0e16\u0e38\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2b\u0e48\u0e2d\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e28. \u0e14\u0e23.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e34\u0e21\u0e1b\u0e34\u0e08\u0e33\u0e19\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e2a\u0e27\u0e17\u0e0a. \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23 \u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e33\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e38\u0e4b\u0e22 \u0e2b\u0e25\u0e31\u0e01-\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e14\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1b\u0e34\u0e14\u0e1c\u0e19\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e16\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e31\u0e19\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-07T08:44:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/\",\"name\":\"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DSC_4357.jpg\",\"datePublished\":\"2023-02-17T10:54:56+00:00\",\"dateModified\":\"2023-03-07T08:44:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DSC_4357.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DSC_4357.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/magik-growth-eeci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 - NSTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/","og_locale":"en_US","og_type":"article","og_title":"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 - NSTDA","og_description":"17 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2566 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e02\u0e15\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 (EECi): \u0e42\u0e14\u0e22 \u0e28. \u0e14\u0e23.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e34\u0e21\u0e1b\u0e34\u0e08\u0e33\u0e19\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.)\u00a0 \u0e19\u0e33\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 Magik Growth\u201d \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e08\u0e13\u0e35 \u0e2d\u0e23\u0e23\u0e16\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e20\u0e34\u0e0d\u0e42\u0e0d \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e14\u0e49\u0e32\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e02\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 (\u0e2a\u0e01\u0e1e\u0e2d.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e15\u0e4c \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19 10,000 \u0e16\u0e38\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2b\u0e48\u0e2d\u0e25\u0e39\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e28. \u0e14\u0e23.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e34\u0e21\u0e1b\u0e34\u0e08\u0e33\u0e19\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e2a\u0e27\u0e17\u0e0a. \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23 \u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e33\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e38\u0e4b\u0e22 \u0e2b\u0e25\u0e31\u0e01-\u0e23\u0e2d\u0e07-\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e14\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1b\u0e34\u0e14\u0e1c\u0e19\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e16\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e31\u0e19\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e30\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e43\u0e19\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2023-03-07T08:44:22+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/","url":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/","name":"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21 - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357.jpg","datePublished":"2023-02-17T10:54:56+00:00","dateModified":"2023-03-07T08:44:22+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2023\/02\/DSC_4357.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/magik-growth-eeci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27","item":"https:\/\/www.nstda.or.th\/home\/news_post\/"},{"@type":"ListItem","position":3,"name":"EECi \u0e2a\u0e27\u0e17\u0e0a. \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u201c\u0e16\u0e38\u0e07\u0e2b\u0e48\u0e2d\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u201d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e23\u0e21"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/40599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/news_post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":4,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/40599\/revisions"}],"predecessor-version":[{"id":40961,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/40599\/revisions\/40961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/40600"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=40599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/categories?post=40599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/tags?post=40599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}