{"id":37761,"date":"2022-11-04T10:06:19","date_gmt":"2022-11-04T03:06:19","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/?post_type=news_post&#038;p=37761"},"modified":"2023-06-11T21:28:37","modified_gmt":"2023-06-11T14:28:37","slug":"bcg-naga-belt-road","status":"publish","type":"news_post","link":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/","title":{"rendered":"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road)"},"content":{"rendered":"<p>For English-version news, please visit : <a href=\"https:\/\/www.nstda.or.th\/en\/news\/news-years-2022\/bcg-naga-belt-road-strengthening-glutinous-rice-farmers-with-modern-agriculture-technology.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.nstda.or.th\/en\/news\/news-years-2022\/bcg-naga-belt-road-strengthening-glutinous-rice-farmers-with-modern-agriculture-technology.html<\/a><\/p>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27\u0e46\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04) \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-NAGA Belt Road)\u201d \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e1b\u0e35 2565 \u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e32\u0e01 \u201c\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u201d \u0e40\u0e1b\u0e47\u0e19 \u201c\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u201d \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-37772\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6524.jpg\" alt=\"\" width=\"2000\" height=\"965\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6524.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6524-300x145.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6524-1024x494.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6524-768x371.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6524-1536x741.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-37774\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30102565.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30102565.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30102565-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30102565-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30102565-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30102565-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>\u0e19.\u0e2a\u0e1e. \u0e22\u0e38\u0e04\u0e25 \u0e25\u0e34\u0e49\u0e21\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 <\/strong><strong>BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19<strong>\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48 <\/strong><strong>3 \u0e2a\u0e39\u0e07 \u0e04\u0e37\u0e2d \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07<\/strong> \u0e42\u0e14\u0e22\u0e21\u0e35\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19<strong>\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (<\/strong><strong>Area based)<\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e44\u0e14\u0e49\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 5 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e41\u0e25\u0e30<strong>\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2d\u0e38\u0e1b\u0e2a\u0e07\u0e04\u0e4c\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (<\/strong><strong>Community based)<\/strong> \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e17\u0e38\u0e01\u0e21\u0e34\u0e15\u0e34\u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e46 \u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d 4P (Public-Private-People-Professional partnership) \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e25\u0e14\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e01\u0e25\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e1b\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e31\u0e49\u0e19\u0e46<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-37775\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC4458-1.jpg\" alt=\"\" width=\"2000\" height=\"1140\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC4458-1.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC4458-1-300x171.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC4458-1-1024x584.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC4458-1-768x438.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC4458-1-1536x876.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>\u0e14\u0e23.\u0e27\u0e23\u0e23\u0e13\u0e1e \u0e27\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e07\u0e27\u0e19 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04) \u0e2a\u0e27\u0e17\u0e0a. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e17\u0e32\u0e07\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30 \u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 <\/strong><strong>BCG \u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23 <\/strong>\u0e44\u0e14\u0e49 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road)\u201d \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG \u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e2a\u0e27\u0e17\u0e0a. \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 (\u0e18.\u0e01.\u0e2a.) \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e22\u0e32\u0e21\u0e04\u0e39\u0e42\u0e1a\u0e15\u0e49\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e34\u0e19\u0e42\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 BCG Model \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e42\u0e14\u0e22\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e37\u0e0a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2a\u0e39\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e34\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37773\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30202565-1.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30202565-1.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30202565-1-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30202565-1-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30202565-1-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/30202565-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>\u0e14\u0e23.\u0e18\u0e35\u0e23\u0e22\u0e38\u0e17\u0e18 \u0e15\u0e39\u0e49\u0e08\u0e34\u0e19\u0e14\u0e32 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 <\/strong><strong>BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 <\/strong>\u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e1b\u0e35 2565 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 BCG-Naga Belt Road \u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 4 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 4 \u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 1. \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 2. \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 3. \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e08\u0e32\u0e01\u0e17\u0e38\u0e19\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30 4. \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 Enabler System \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e15\u0e32\u0e21 BCG model<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37767\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6393.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6393.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6393-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6393-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6393-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6393-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>@\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e01\u0e23\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 <\/strong><\/p>\n<p>\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u00a0\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e21\u0e35<strong> \u0e14\u0e23.\u0e01\u0e31\u0e0d\u0e0d\u0e13\u0e31\u0e0a \u0e28\u0e34\u0e23\u0e34\u0e18\u0e31\u0e0d\u0e0d\u0e32 <\/strong>\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e25\u0e14\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e41\u0e2b\u0e19\u0e41\u0e14\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e48\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 16 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e46 \u0e25\u0e30 50 \u0e04\u0e19 \u0e15\u0e48\u0e2d\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21 3,200 \u0e04\u0e19 \u0e43\u0e19 4 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19 3 \u0e23\u0e30\u0e14\u0e31\u0e1a \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e21\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e02\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e19 \u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 11 \u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 7 \u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 9 \u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e41\u0e25\u0e30 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 10 \u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07 4 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e27\u0e21 24,152 \u0e44\u0e23\u0e48 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e08\u0e33\u0e19\u0e27\u0e19 724,586 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 63,114,689 \u0e1a\u0e32\u0e17<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37771\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6428.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6428.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6428-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6428-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6428-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6428-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p>\u201c\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e49\u0e32\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e42\u0e1e\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27 4,634.7 \u0e44\u0e23\u0e48 \u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14 1-2 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e19\u0e41\u0e14\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e19\u0e32\u0e02\u0e49\u0e32\u0e27 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e01\u0e4a\u0e32\u0e0b\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 419.85 \u0e15\u0e31\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e23\u0e32\u0e04\u0e32\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15 398,223 \u0e1a\u0e32\u0e17 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e01\u0e4a\u0e32\u0e0b\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 9.75 \u0e15\u0e31\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e23\u0e32\u0e04\u0e32\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15 9,251 \u0e1a\u0e32\u0e17 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37763\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6332.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6332.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6332-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6332-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6332-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6332-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>@\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 Circular economy \u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e15\u0e48\u0e33<\/strong><\/p>\n<p>\u0e14\u0e23.\u0e18\u0e35\u0e23\u0e22\u0e38\u0e17\u0e18 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32 \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e19\u0e31\u0e49\u0e19\u0e21\u0e35<strong> \u0e14\u0e23.\u0e2a\u0e38\u0e23\u0e1e\u0e25 \u0e43\u0e08\u0e27\u0e07\u0e28\u0e4c\u0e29\u0e32 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e25\u0e33\u0e1b\u0e32\u0e07<\/strong>\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 173 \u0e23\u0e32\u0e22 \u00a0\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e34\u0e49\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e41\u0e1c\u0e48\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e1f\u0e32\u0e07\u0e02\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 (Particle Board) \u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e46 \u00a0\u0e2a\u0e39\u0e48\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e2b\u0e31\u0e15\u0e16\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e08\u0e32\u0e01\u0e1f\u0e32\u0e07\u0e02\u0e49\u0e32\u0e27 (Biomaterial) \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2b\u0e47\u0e14\u0e08\u0e32\u0e01\u0e1f\u0e32\u0e07\u0e02\u0e49\u0e32\u0e27 \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 Geopolymer \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e01\u0e25\u0e1a\u0e14\u0e33\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e16\u0e49\u0e32\u0e25\u0e2d\u0e22\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e14\u0e34\u0e19\u0e1b\u0e25\u0e39\u0e01\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01\u0e40\u0e16\u0e49\u0e32\u0e25\u0e2d\u0e22\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25\u00a0 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e14\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01\u0e41\u0e2b\u0e19\u0e41\u0e14\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e2a\u0e35\u0e22\u0e49\u0e2d\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e32\u0e01\u0e17\u0e38\u0e48\u0e07\u0e19\u0e32\u0e2a\u0e39\u0e48\u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37764\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6334.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6334.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6334-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6334-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6334-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6334-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23 Reskill-upskill \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e43\u0e19\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e1e \u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e1a\u0e23\u0e21 \u0e21\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 80 \u0e23\u0e32\u0e22 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 131 \u0e23\u0e32\u0e22 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e23\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 115 \u0e23\u0e32\u0e22 \u0e41\u0e25\u0e30 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e2a\u0e35 40 \u0e23\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 <strong>\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e22\u0e32\u0e21\u0e04\u0e39\u0e42\u0e1a\u0e15\u0e49\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e34\u0e19\u0e42\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e18.\u0e01.\u0e2a.<\/strong> \u0e14\u0e49\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 Creative Design Thinking \u0e41\u0e25\u0e30 Workshop \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 40 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e14\u0e49\u0e32\u0e19 carbon credit \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 ecosystem \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e15\u0e48\u0e33<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37765\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6338.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6338.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6338-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6338-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6338-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6338-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>@\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e2d\u0e17\u0e42\u0e23\u0e04\u0e02\u0e49\u0e32\u0e27 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e42\u0e23\u0e04\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48<\/strong><\/p>\n<p><strong>\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 <\/strong><strong>Enabler System \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e15\u0e32\u0e21 BCG model <\/strong>\u0e21\u0e35<strong> \u0e14\u0e23.\u0e2a\u0e38\u0e08\u0e34\u0e19\u0e15\u0e4c \u0e20\u0e31\u0e17\u0e23\u0e20\u0e39\u0e27\u0e14\u0e25 <\/strong>\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e43\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e42\u0e23\u0e04\u0e02\u0e49\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c LineBoT \u0e42\u0e23\u0e04\u0e02\u0e49\u0e32\u0e27 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07<strong>\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e42\u0e23\u0e04\u0e1e\u0e37\u0e0a \u0e04\u0e13\u0e30\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c <\/strong>\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 BCG Naga Belt Road \u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e35\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e21\u0e17\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49<strong>\u0e23\u0e28.\u0e14\u0e23.\u0e40\u0e02\u0e21\u0e23\u0e31\u0e10 \u0e40\u0e16\u0e25\u0e34\u0e07\u0e28\u0e23\u0e35 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e08\u0e32\u0e01\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 <\/strong>\u0e44\u0e14\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e10\u0e32\u0e19\u0e17\u0e38\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e1b\u0e0f\u0e34\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e10\u0e32\u0e19\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e10\u0e32\u0e19\u0e17\u0e38\u0e19\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e23\u0e32\u0e22\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 BCG \u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37768\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6403.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6403.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6403-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6403-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6403-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6403-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><strong>@\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01 \u0e0a\u0e39\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1a\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 <\/strong><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e08\u0e32\u0e01\u0e17\u0e38\u0e19\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e21\u0e35<strong> \u0e14\u0e23.\u0e2d\u0e23\u0e23\u0e08\u0e19\u0e32 \u0e14\u0e49\u0e27\u0e07\u0e41\u0e1e\u0e07 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 <\/strong>\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e25\u0e32\u0e14\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e43\u0e19<strong>\u0e08.\u0e23\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e32\u0e0a\u0e21\u0e07\u0e04\u0e25\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 <\/strong>\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e39\u0e48\u0e04\u0e25\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e15\u0e25\u0e32\u0e14\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37766\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6378.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6378.jpg 2000w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6378-300x200.jpg 300w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6378-1024x682.jpg 1024w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6378-768x512.jpg 768w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/DSC_6378-1536x1024.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><em>\u201c\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (<\/em><em>BCG-Naga Belt Road)\u201d \u0e40\u0e1b\u0e47\u0e19 Quick Win \u0e02\u0e2d\u0e07 BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e35\u0e48\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e41\u0e1a\u0e1a 4P (Public-Private-People-Professional partnership) \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 BCG \u0e41\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (Area based) \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u201d <\/em><strong>\u0e14\u0e23.\u0e18\u0e35\u0e23\u0e22\u0e38\u0e17\u0e18 <\/strong>\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22<\/p>\n","protected":false},"author":16,"featured_media":37776,"template":"","categories":[253],"tags":[3112,3111,899,2241],"class_list":["post-37761","news_post","type-news_post","status-publish","has-post-thumbnail","hentry","category-pr-cat","tag-bcgnagabeltroad","tag-nagabeltroad","tag-bcg","tag-bcgmodel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road) - NSTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road) - NSTDA\" \/>\n<meta property=\"og:description\" content=\"For English-version news, please visit : https:\/\/www.nstda.or.th\/en\/news\/news-years-2022\/bcg-naga-belt-road-strengthening-glutinous-rice-farmers-with-modern-agriculture-technology.html \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27\u0e46\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04) \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-NAGA Belt Road)\u201d \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e1b\u0e35 2565 \u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e32\u0e01 \u201c\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u201d \u0e40\u0e1b\u0e47\u0e19 \u201c\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u201d \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e19.\u0e2a\u0e1e. \u0e22\u0e38\u0e04\u0e25 \u0e25\u0e34\u0e49\u0e21\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48 3 \u0e2a\u0e39\u0e07 \u0e04\u0e37\u0e2d \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (Area based) \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e44\u0e14\u0e49\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 5 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-11T14:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/New-Project-30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/\",\"name\":\"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road) - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/New-Project-30.jpg\",\"datePublished\":\"2022-11-04T03:06:19+00:00\",\"dateModified\":\"2023-06-11T14:28:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/New-Project-30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/New-Project-30.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-naga-belt-road\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road) - NSTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/","og_locale":"en_US","og_type":"article","og_title":"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road) - NSTDA","og_description":"For English-version news, please visit : https:\/\/www.nstda.or.th\/en\/news\/news-years-2022\/bcg-naga-belt-road-strengthening-glutinous-rice-farmers-with-modern-agriculture-technology.html \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27\u0e46\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e42\u0e14\u0e22\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04) \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e25\u0e33\u0e1b\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-NAGA Belt Road)\u201d \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e1b\u0e35 2565 \u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e32\u0e01 \u201c\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u201d \u0e40\u0e1b\u0e47\u0e19 \u201c\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e02\u0e49\u0e32\u0e27\u201d \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e19.\u0e2a\u0e1e. \u0e22\u0e38\u0e04\u0e25 \u0e25\u0e34\u0e49\u0e21\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 BCG \u0e2a\u0e32\u0e02\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48 3 \u0e2a\u0e39\u0e07 \u0e04\u0e37\u0e2d \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (Area based) \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e44\u0e14\u0e49\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 5 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2023-06-11T14:28:37+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/New-Project-30.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/","url":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/","name":"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road) - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/New-Project-30.jpg","datePublished":"2022-11-04T03:06:19+00:00","dateModified":"2023-06-11T14:28:37+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/New-Project-30.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/11\/New-Project-30.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-naga-belt-road\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27","item":"https:\/\/www.nstda.or.th\/home\/news_post\/"},{"@type":"ListItem","position":3,"name":"\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e42\u0e02\u0e07 (BCG-Naga Belt Road)"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/37761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/news_post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":5,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/37761\/revisions"}],"predecessor-version":[{"id":43899,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/37761\/revisions\/43899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/37776"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=37761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/categories?post=37761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/tags?post=37761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}