{"id":35943,"date":"2022-09-14T14:58:35","date_gmt":"2022-09-14T07:58:35","guid":{"rendered":"https:\/\/www.nstda.or.th\/home\/?post_type=news_post&#038;p=35943"},"modified":"2023-03-08T15:43:10","modified_gmt":"2023-03-08T08:43:10","slug":"bcg-happy-story-thungsong-hometown","status":"publish","type":"news_post","link":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/","title":{"rendered":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"35943\" class=\"elementor elementor-35943\" data-elementor-post-type=\"news_post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f3b8c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f3b8c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51fb28b\" data-id=\"51fb28b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e34f74 elementor-widget elementor-widget-video\" data-id=\"1e34f74\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=yRNQpN2CsSo&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9680d87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9680d87\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13dc4fc\" data-id=\"13dc4fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b135589 elementor-widget elementor-widget-text-editor\" data-id=\"b135589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <em>\u201c<\/em><\/strong><em>\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d <\/em><em>3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d<\/em> \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 <em>\u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23<\/em><em>?\u201d<\/em><\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c : <em>\u201cB \u0e04\u0e37\u0e2d Bioeconomy, C \u0e04\u0e37\u0e2d Circular Economy \u0e41\u0e25\u0e30 G \u0e04\u0e37\u0e2d Green Economy \u0e40\u0e23\u0e35\u0e22\u0e01\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e27\u0e48\u0e32 BCG 3 \u0e15\u0e31\u0e27\u0e15\u0e23\u0e07 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/em> <em>\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e08\u0e30\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e2b\u0e27\u0e22 \u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e40\u0e21\u0e01\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e22\u0e39\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e19\u0e08\u0e4c\u0e22\u0e31\u0e27\u0e21\u0e32\u0e22\u0e14\u0e4c\u0e40\u0e0b\u0e15 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e43\u0e01\u0e25\u0e49\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e42\u0e25\u0e01\u0e14\u0e49\u0e27\u0e22\u201d<\/em><\/p><p>\u0e1a\u0e17\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e44\u0e2d\u0e0b\u0e4c\u0e2b\u0e0d\u0e34\u0e07\u0e2a\u0e32\u0e27\u0e1c\u0e39\u0e49\u0e21\u0e32\u0e02\u0e2d\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e25\u0e34\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 <strong>\u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019<\/strong> \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e42\u0e14\u0e22\u0e17\u0e35\u0e21 Thungsong Hometown \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 <a href=\"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story\/\"><strong>\u201c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d <\/strong><strong>BCG Happy Story: \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e43\u0e08\u201d<\/strong><\/a> \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e25\u0e34\u0e1b\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27 30-60 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e17\u0e35\u0e21 Thungsong Hometown \u0e08\u0e30\u0e21\u0e32\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e25\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d9981c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d9981c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bf83e09\" data-id=\"bf83e09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17ca217\" data-id=\"17ca217\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e7f1dd elementor-widget elementor-widget-image\" data-id=\"6e7f1dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_2.jpg\" class=\"attachment-large size-large wp-image-35957\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_2.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_2-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5badf33\" data-id=\"5badf33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdee78f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdee78f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc4c603\" data-id=\"cc4c603\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-898a9ab elementor-widget elementor-widget-heading\" data-id=\"898a9ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a Thungsong Hometown <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d64290f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d64290f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-733c173\" data-id=\"733c173\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddfc0a elementor-widget elementor-widget-text-editor\" data-id=\"8ddfc0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e04\u0e33\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1a\u0e2d\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19 Thungsong Hometown \u0e44\u0e14\u0e49\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e04\u0e37\u0e2d \u0e17\u0e35\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u0e17\u0e35\u0e48\u0e23\u0e27\u0e21\u0e15\u0e31\u0e27\u0e01\u0e31\u0e19\u0e21\u0e32\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e42\u0e0a\u0e01\u0e42\u0e0a\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d250013 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d250013\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a45ccae\" data-id=\"a45ccae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9df7f3d\" data-id=\"9df7f3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84a68f7 elementor-widget elementor-widget-image\" data-id=\"84a68f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"432\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_9.jpg\" class=\"attachment-large size-large wp-image-35944\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_9.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_9-300x202.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b90c014\" data-id=\"b90c014\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2bfe28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2bfe28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a3a404\" data-id=\"0a3a404\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1186836 elementor-widget elementor-widget-text-editor\" data-id=\"1186836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e43\u0e08\u0e2b\u0e25\u0e48\u0e2d<\/strong> \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e21 Thungsong Hometown \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e17\u0e35\u0e21 Thungsong Hometown \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e23\u0e27\u0e21\u0e15\u0e31\u0e27\u0e01\u0e31\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e17\u0e35\u0e21\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e40\u0e27\u0e17\u0e35\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 5 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e21\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 <strong>\u2018\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e49\u0e33\u2019<\/strong> \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 <strong>\u2018\u0e2b\u0e2d\u0e21\u0e40\u0e04\u0e22\u2019<\/strong> \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e23\u0e2d\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e37\u0e48\u0e2d \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e22\u0e32\u0e01\u0e2a\u0e38\u0e14\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e40\u0e08\u0e2d\u0e21\u0e32 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 1 \u0e19\u0e32\u0e17\u0e35 <strong><em>\u0e41\u0e15\u0e48\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e2d\u0e32\u0e0a\u0e19\u0e30\u0e14\u0e39<\/em><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8152617 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8152617\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2aee8f6\" data-id=\"2aee8f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-844697c elementor-widget elementor-widget-text-editor\" data-id=\"844697c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201c\u0e1e\u0e2d\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e25\u0e07\u0e41\u0e02\u0e48\u0e07 \u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e04\u0e37\u0e2d \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e32\u0e01\u0e41\u0e19\u0e48\u0e46 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e22\u0e2d\u0e30\u0e21\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e44\u0e14\u0e49\u0e25\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e38\u0e1b\u0e43\u0e08\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e40\u0e23\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e22\u0e32\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e01\u0e25\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14 \u0e17\u0e35\u0e21\u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32<strong><em> \u0e19\u0e48\u0e32\u0e08\u0e30\u0e19\u0e33\u0e43\u0e08\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08<\/em><\/strong><strong><em> BCG \u0e21\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e49\u0e19 \u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e04\u0e19\u0e14\u0e39\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32\u0e44\u0e14\u0e49 \u0e16\u0e49\u0e32\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e19\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e19\u0e43\u0e08 \u0e14\u0e39\u0e44\u0e14\u0e49\u0e08\u0e19\u0e08\u0e1a\u0e04\u0e25\u0e34\u0e1b\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e1b\u0e34\u0e14\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19<\/em><\/strong>\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9df55c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9df55c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed9bc09\" data-id=\"ed9bc09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf07e9d elementor-widget elementor-widget-text-editor\" data-id=\"bf07e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e25\u0e34\u0e1b\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e42\u0e14\u0e22 Thungsong Hometown \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e14\u0e41\u0e19\u0e48\u0e19\u0e21\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e23\u0e35\u0e22\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32 1 \u0e19\u0e32\u0e17\u0e35 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e49\u0e2d\u0e22\u0e23\u0e27\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e1a\u0e40\u0e19\u0e35\u0e22\u0e19 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e14\u0e36\u0e07\u0e41\u0e01\u0e48\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e25\u0e35\u0e40\u0e14\u0e47\u0e14\u0e17\u0e35\u0e48\u0e42\u0e14\u0e19\u0e43\u0e08\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e2b\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1309472 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1309472\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c782c36\" data-id=\"c782c36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-708a3b4 elementor-widget elementor-widget-text-editor\" data-id=\"708a3b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e17\u0e35\u0e21\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e14\u0e39\u0e2b\u0e31\u0e19\u0e21\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e0b\u0e36\u0e48\u0e07\u0e14\u0e39\u0e44\u0e01\u0e25\u0e15\u0e31\u0e27\u0e19\u0e48\u0e32\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2a\u0e19\u0e43\u0e08\u0e21\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14 \u0e42\u0e0a\u0e04\u0e14\u0e35\u0e15\u0e2d\u0e19\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1c\u0e2d\u0e34\u0e0d\u0e21\u0e35\u0e02\u0e48\u0e32\u0e27\u0e02\u0e39\u0e14\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e02\u0e2d\u0e2b\u0e27\u0e22 \u0e40\u0e25\u0e22\u0e1b\u0e34\u0e4a\u0e07\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e49\u0e2b\u0e27\u0e22\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e41\u0e17\u0e19 \u0e01\u0e47\u0e19\u0e48\u0e32\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e31\u0e01\u0e21\u0e38\u0e21\u0e14\u0e35 <strong><em>\u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e0a\u0e27\u0e19\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e27\u0e34\u0e18\u0e35\u0e23\u0e27\u0e22\u0e17\u0e32\u0e07\u0e25\u0e31\u0e14 \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e17\u0e19 (\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30)<\/em><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48b9294 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48b9294\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01265c8\" data-id=\"01265c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-649d165 elementor-widget elementor-widget-text-editor\" data-id=\"649d165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201c\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e47\u0e2d\u0e15\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e17\u0e35\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e27\u0e49\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e04\u0e19\u0e14\u0e39\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e44\u0e1b\u0e2a\u0e37\u0e1a\u0e04\u0e49\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e08\u0e32\u0e01\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e14\u0e39\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22 2 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e04\u0e25\u0e34\u0e1b \u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e19\u0e33\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e32\u0e01\u0e43\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e21\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 (\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 Para Plearn \u0e42\u0e14\u0e22\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e17\u0e04 \u0e2a\u0e27\u0e17\u0e0a.) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e22\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e25\u0e14\u0e01\u0e32\u0e23\u0e17\u0e33\u0e25\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 (\u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07) <strong><em>\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e04\u0e34\u0e14\u0e27\u0e34\u0e18\u0e35\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e08\u0e14\u0e08\u0e33\u0e04\u0e35\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e14\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 <\/em><\/strong>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e21\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e02\u0e35\u0e22\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e02\u0e49\u0e32\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e41\u0e23\u0e01\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14b49e7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14b49e7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34affd19\" data-id=\"34affd19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-68ad9f2c\" data-id=\"68ad9f2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41605cbf elementor-widget elementor-widget-image\" data-id=\"41605cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"453\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_14.jpg\" class=\"attachment-large size-large wp-image-35949\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_14.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_14-300x212.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4172049d\" data-id=\"4172049d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43cabbd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43cabbd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-189cae84\" data-id=\"189cae84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-60c8ac7a\" data-id=\"60c8ac7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cf03058 elementor-widget elementor-widget-image\" data-id=\"4cf03058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"453\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_15.jpg\" class=\"attachment-large size-large wp-image-35950\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_15.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_15-300x212.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19a2d26f\" data-id=\"19a2d26f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aba92ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aba92ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4b15d7\" data-id=\"d4b15d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e8f090 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e8f090\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4a5946cc\" data-id=\"4a5946cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d9ce57a\" data-id=\"5d9ce57a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3495f108 elementor-widget elementor-widget-image\" data-id=\"3495f108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"453\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_16.jpg\" class=\"attachment-large size-large wp-image-35951\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_16.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_16-300x212.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5e31c9ad\" data-id=\"5e31c9ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aded930 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aded930\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8de7867\" data-id=\"8de7867\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c243bbc elementor-widget elementor-widget-heading\" data-id=\"c243bbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0e1e\u0e23\u0e35 \u0e42\u0e1e\u0e23 \u0e42\u0e1e\u0e2a\u0e15\u0e4c \u0e42\u0e2b\u0e14\u0e2a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e02\u0e39\u0e14\u0e2b\u0e27\u0e22<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c14ce8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c14ce8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a16fb2\" data-id=\"5a16fb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b251bf5 elementor-widget elementor-widget-text-editor\" data-id=\"b251bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e2a\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e21\u0e04\u0e23\u0e36\u0e48\u0e07 \u0e15\u0e34\u0e4a\u0e07! \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e40\u0e14\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e34\u0e19\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c\u2026\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e04\u0e27\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e21\u0e32\u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e01\u0e47\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e19\u0e31\u0e48\u0e07\u0e22\u0e34\u0e49\u0e21\u0e01\u0e23\u0e34\u0e48\u0e21\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 <strong>\u2018\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49 3 \u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u0e41\u0e25\u0e49\u0e27\u0e19\u0e30\u2019<\/strong> (\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e21) Thungsong Hometown \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48 6 \u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e02\u0e49\u0e32\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e1f\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e2d\u0e35\u0e01 118 \u0e17\u0e35\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e2d\u0e1a\u0e0a\u0e34\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28 \u0e41\u0e15\u0e48\u0e41\u0e25\u0e49\u0e27\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e21\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e1a\u0e2d\u0e01\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 <strong><em>\u2018\u0e41\u0e21\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e38\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e08\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u2019<\/em><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8807b65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8807b65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c152f1a\" data-id=\"c152f1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83c826c elementor-widget elementor-widget-text-editor\" data-id=\"83c826c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e2d\u0e1a\u0e14\u0e35\u0e43\u0e08\u0e21\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e43\u0e2b\u0e49\u0e17\u0e35\u0e21\u0e25\u0e38\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2b\u0e32\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e19\u0e32\u0e07\u0e40\u0e2d\u0e01\u0e08\u0e30\u0e44\u0e1b\u0e02\u0e39\u0e14\u0e2b\u0e27\u0e22\u0e02\u0e2d\u0e1e\u0e23 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e27\u0e48\u0e32 <strong><em>\u2018\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e2d\u0e19\u0e14\u0e35\u0e19\u0e30\u2019<\/em><\/strong> (\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30) \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e43\u0e19\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e35\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e16\u0e39\u0e01\u0e43\u0e08\u0e43\u0e19\u0e27\u0e34\u0e27\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e09\u0e32\u0e01\u0e1b\u0e34\u0e14 \u0e04\u0e37\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e35\u0e23\u0e35\u0e27\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 60 \u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23 \u0e41\u0e21\u0e49\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19\u0e08\u0e30\u0e44\u0e01\u0e25\u0e41\u0e15\u0e48\u0e27\u0e34\u0e27\u0e01\u0e47\u0e2a\u0e27\u0e22\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e01<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-437c123e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"437c123e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fa242fc\" data-id=\"fa242fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-78f074d\" data-id=\"78f074d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a335b27 elementor-widget elementor-widget-image\" data-id=\"2a335b27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_10.jpg\" class=\"attachment-large size-large wp-image-35945\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_10.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_10-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d763067\" data-id=\"1d763067\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac78049 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac78049\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-779ff108\" data-id=\"779ff108\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-20dd49d\" data-id=\"20dd49d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5891949d elementor-widget elementor-widget-image\" data-id=\"5891949d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg\" class=\"attachment-large size-large wp-image-35952\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-79743b38\" data-id=\"79743b38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28c983af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28c983af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6365064e\" data-id=\"6365064e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6418c576\" data-id=\"6418c576\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-473a8471 elementor-widget elementor-widget-image\" data-id=\"473a8471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_18.jpg\" title=\"thungsong_18\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f45f78c\" data-id=\"f45f78c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4df5cae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4df5cae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e06a1a6\" data-id=\"e06a1a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14860d3 elementor-widget elementor-widget-text-editor\" data-id=\"14860d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e09\u0e32\u0e01\u0e02\u0e39\u0e14\u0e2b\u0e27\u0e22 \u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e25\u0e34\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0a\u0e48\u0e27\u0e07 4-6 \u0e42\u0e21\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e42\u0e1e\u0e25\u0e49\u0e40\u0e1e\u0e25\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e02\u0e2d\u0e07\u0e0b\u0e35\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e2d\u0e32\u0e40\u0e02\u0e49\u0e32\u0e08\u0e23\u0e34\u0e07\u0e40\u0e27\u0e25\u0e32 2 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e15\u0e36\u0e07\u0e40\u0e2d\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e40\u0e0b\u0e15\u0e1e\u0e23\u0e47\u0e2d\u0e1b\u0e1b\u0e31\u0e01\u0e40\u0e17\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e17\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e49\u0e27 \u0e27\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e25\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e33\u0e46 \u0e0b\u0e49\u0e33\u0e40\u0e15\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e22\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19\u0e17\u0e35\u0e21\u0e16\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19 \u0e04\u0e31\u0e15\u0e17\u0e35\u0e01\u0e47\u0e02\u0e33\u0e01\u0e25\u0e34\u0e49\u0e07\u0e17\u0e35 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e31\u0e49\u0e07 2 \u0e04\u0e19 \u0e41\u0e2a\u0e14\u0e07\u0e40\u0e01\u0e48\u0e07\u0e21\u0e32\u0e01 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e1a\u0e17\u0e01\u0e31\u0e19\u0e21\u0e32\u0e14\u0e35 \u0e15\u0e35\u0e1a\u0e17\u0e41\u0e15\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e02\u0e22\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e04\u0e34\u0e14\u0e21\u0e38\u0e01\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e17\u0e2a\u0e19\u0e38\u0e01\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e17\u0e35\u0e48\u0e04\u0e35\u0e23\u0e35\u0e27\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e43\u0e19\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14 \u0e09\u0e32\u0e01\u0e19\u0e35\u0e49\u0e16\u0e48\u0e32\u0e22\u0e07\u0e48\u0e32\u0e22\u0e01\u0e27\u0e48\u0e32\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1a\u0e17\u0e44\u0e21\u0e48\u0e40\u0e22\u0e2d\u0e30 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e44\u0e21\u0e48\u0e21\u0e32\u0e01 \u0e22\u0e32\u0e01\u0e41\u0e04\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25 (\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30)\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75996e91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75996e91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f55bcd3\" data-id=\"2f55bcd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4d7ecfca\" data-id=\"4d7ecfca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57ea80e2 elementor-widget elementor-widget-image\" data-id=\"57ea80e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"408\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_3.jpg\" class=\"attachment-large size-large wp-image-35958\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_3.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_3-300x191.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7b432939\" data-id=\"7b432939\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18f0b59b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18f0b59b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7768b036\" data-id=\"7768b036\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-337d1677\" data-id=\"337d1677\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eb6c335 elementor-widget elementor-widget-image\" data-id=\"3eb6c335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_11.jpg\" class=\"attachment-large size-large wp-image-35946\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_11.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_11-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5cb9a63f\" data-id=\"5cb9a63f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41458085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41458085\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-37fb3743\" data-id=\"37fb3743\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3a2c1388\" data-id=\"3a2c1388\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cbeee01 elementor-widget elementor-widget-image\" data-id=\"3cbeee01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"369\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_6.jpg\" class=\"attachment-large size-large wp-image-35961\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_6.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_6-300x173.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5ddddb3\" data-id=\"5ddddb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6299b596 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6299b596\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-284ad984\" data-id=\"284ad984\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3fcfbcbb\" data-id=\"3fcfbcbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23a1a4e6 elementor-widget elementor-widget-image\" data-id=\"23a1a4e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_12.jpg\" class=\"attachment-large size-large wp-image-35947\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_12.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_12-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c61f341\" data-id=\"5c61f341\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52c1b2ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52c1b2ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12f71497\" data-id=\"12f71497\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-668550bb\" data-id=\"668550bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-571d12a6 elementor-widget elementor-widget-image\" data-id=\"571d12a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"515\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_13.jpg\" class=\"attachment-large size-large wp-image-35948\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_13.jpg 500w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_13-291x300.jpg 291w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-66c3baa6\" data-id=\"66c3baa6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d0f1b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d0f1b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7381cea\" data-id=\"7381cea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c9bb26 elementor-widget elementor-widget-text-editor\" data-id=\"8c9bb26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e08\u0e1a \u0e07\u0e32\u0e19\u0e44\u0e21\u0e48\u0e08\u0e1a \u0e22\u0e31\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e34\u0e14\u0e08\u0e47\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e21 Thungsong Hometown \u0e04\u0e37\u0e2d \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e43\u0e08\u0e43\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e08\u0e30\u0e42\u0e04\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e25\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e25\u0e07\u0e15\u0e31\u0e27<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5bffe2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5bffe2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eed90f9\" data-id=\"eed90f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91d91e4 elementor-widget elementor-widget-text-editor\" data-id=\"91d91e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e2b\u0e25\u0e31\u0e07\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e08\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e01\u0e21\u0e32\u0e15\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e21\u0e42\u0e1e\u0e2a\u0e15\u0e4c (\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30) \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e17\u0e35\u0e21\u0e14\u0e39\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e01\u0e31\u0e19\u0e40\u0e22\u0e2d\u0e30\u0e21\u0e32\u0e01 <strong><em>\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e04\u0e25\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e22\u0e49\u0e2d\u0e21\u0e2a\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e21\u0e32\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1e\u0e25\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e47\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e08\u0e30\u0e42\u0e04\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e23\u0e23\u0e16\u0e23\u0e2a\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/em><\/strong> \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e17\u0e35\u0e21\u0e41\u0e25\u0e30\u0e04\u0e23\u0e39\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e21\u0e32\u0e19\u0e31\u0e48\u0e07\u0e14\u0e39\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22 \u0e1e\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e14\u0e39\u0e41\u0e25\u0e49\u0e27\u0e2a\u0e19\u0e38\u0e01 \u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e35\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e2d\u0e1a\u0e0a\u0e34\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30bd17e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30bd17e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b175ff2\" data-id=\"3b175ff2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b647735\" data-id=\"5b647735\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5080bee2 elementor-widget elementor-widget-image\" data-id=\"5080bee2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"346\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_5.jpg\" class=\"attachment-large size-large wp-image-35960\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_5.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_5-300x162.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1be43e9b\" data-id=\"1be43e9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bbf8942 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bbf8942\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4e11e1ff\" data-id=\"4e11e1ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7e9fbec1\" data-id=\"7e9fbec1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-694adc5 elementor-widget elementor-widget-image\" data-id=\"694adc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"346\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_4.png\" class=\"attachment-large size-large wp-image-35959\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_4.png 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_4-300x162.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-22d3aeac\" data-id=\"22d3aeac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-321dcf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"321dcf4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4dc2e8a5\" data-id=\"4dc2e8a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67a35c66\" data-id=\"67a35c66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58515c74 elementor-widget elementor-widget-image\" data-id=\"58515c74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_19.jpg\" class=\"attachment-large size-large wp-image-35954\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_19.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_19-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cb84792\" data-id=\"cb84792\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37219353 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37219353\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-76501ac\" data-id=\"76501ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-188cf87c\" data-id=\"188cf87c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bdcb2ab elementor-widget elementor-widget-image\" data-id=\"7bdcb2ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_20.jpg\" class=\"attachment-large size-large wp-image-35955\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_20.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_20-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-730499aa\" data-id=\"730499aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8cbee18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8cbee18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4226fb8\" data-id=\"4226fb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4fd92f elementor-widget elementor-widget-heading\" data-id=\"b4fd92f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e25\u0e48\u0e32\u0e0b\u0e49\u0e33\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e2d\u0e1a<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86176eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86176eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3b35ae\" data-id=\"e3b35ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b89129b elementor-widget elementor-widget-text-editor\" data-id=\"b89129b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>\u2018BCG \u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e21\u0e48 \u0e14\u0e35\u0e15\u0e48\u0e2d\u0e43\u0e08 \u0e14\u0e35\u0e15\u0e48\u0e2d\u0e44\u0e17\u0e22 \u0e14\u0e35\u0e15\u0e48\u0e2d\u0e42\u0e25\u0e01\u2019<\/em><\/strong> \u0e04\u0e37\u0e2d \u0e27\u0e25\u0e35\u0e15\u0e34\u0e14\u0e2b\u0e39\u0e1a\u0e17\u0e2a\u0e23\u0e38\u0e1b\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 <strong>\u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 <\/strong>\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e2d\u0e19 \u0e15\u0e25\u0e01 \u0e2b\u0e31\u0e01\u0e21\u0e38\u0e21 \u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e23\u0e2a \u0e41\u0e21\u0e49\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e08\u0e30\u0e08\u0e1a\u0e25\u0e07\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e41\u0e15\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e22\u0e32\u0e27\u0e46 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28da86d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28da86d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae3750a\" data-id=\"ae3750a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96cb78c elementor-widget elementor-widget-text-editor\" data-id=\"96cb78c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e40\u0e25\u0e48\u0e32\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e22\u0e2d\u0e30\u0e21\u0e32\u0e01 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e41\u0e23\u0e01\u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e01\u0e47\u0e04\u0e07\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e44\u0e14\u0e49\u0e25\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e08\u0e23\u0e34\u0e07\u0e08\u0e31\u0e07 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e01\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07 \u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e49\u0e19\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e04\u0e19\u0e14\u0e39\u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e23\u0e23\u0e16\u0e23\u0e2a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e08\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e04\u0e23\u0e1a\u0e16\u0e49\u0e27\u0e19\u0e14\u0e49\u0e27\u0e22<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-178122a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"178122a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ee0916\" data-id=\"5ee0916\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4cf546 elementor-widget elementor-widget-text-editor\" data-id=\"c4cf546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201c<strong><em>\u0e40\u0e23\u0e32\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19 <\/em><\/strong><strong><em>\u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 BCG \u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e23\u0e32\u0e08\u0e30\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e44\u0e1b\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e43\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e48\u0e2d\u0e44\u0e1b<\/em><\/strong> <strong><em>\u0e17\u0e35\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/em><\/strong><strong>\u201d <\/strong>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e34\u0e49\u0e07\u0e17\u0e49\u0e32\u0e22<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65be71a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65be71a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-18eacb88\" data-id=\"18eacb88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6fa6fc\" data-id=\"6fa6fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3435de75 elementor-widget elementor-widget-image\" data-id=\"3435de75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"486\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_8.jpg\" class=\"attachment-large size-large wp-image-35963\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_8.jpg 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_8-300x228.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5ef3a842\" data-id=\"5ef3a842\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-194ed4f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"194ed4f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4351b6a7\" data-id=\"4351b6a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-347d0687\" data-id=\"347d0687\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55c1f35d elementor-widget elementor-widget-image\" data-id=\"55c1f35d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"483\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_7.jpg\" class=\"attachment-large size-large wp-image-35962\" alt=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_7.jpg 697w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_7-300x226.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b99976b\" data-id=\"3b99976b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f949590 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f949590\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed32ded\" data-id=\"ed32ded\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf70ff3 elementor-widget elementor-widget-heading\" data-id=\"bf70ff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Thungsong Hometown<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d00c14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d00c14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d22676\" data-id=\"5d22676\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90930aa elementor-widget elementor-widget-text-editor\" data-id=\"90930aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e43\u0e08\u0e2b\u0e25\u0e48\u0e2d (\u0e40\u0e04) <\/strong>\u2013 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e21 \u0e1c\u0e39\u0e49\u0e17\u0e33\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1e\u0e23\u0e35-\u0e42\u0e1e\u0e23-\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19\u00a0<\/li><li><strong>\u0e19\u0e1e\u0e14\u0e25 \u0e44\u0e01\u0e23\u0e19\u0e23\u0e32 (\u0e41\u0e1a\u0e07\u0e04\u0e4c) <\/strong>\u2013 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1a\u0e17\u0e1a\u0e32\u0e17 \u0e2a\u0e19\u0e38\u0e01 \u0e15\u0e25\u0e01 \u0e04\u0e23\u0e1a\u0e43\u0e19\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27<\/li><li><strong>\u0e1e\u0e31\u0e17\u0e18\u0e4c\u0e18\u0e35\u0e23\u0e32 \u0e2b\u0e21\u0e27\u0e14\u0e17\u0e2d\u0e07 (\u0e44\u0e2d\u0e0b\u0e4c) <\/strong>\u2013 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e2a\u0e32\u0e27\u0e02\u0e39\u0e14\u0e2b\u0e27\u0e22 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e32\u0e27\u0e2a\u0e27\u0e22\u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e32\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e07\u0e15\u0e31\u0e27<\/li><li><strong>\u0e13\u0e31\u0e10\u0e20\u0e39\u0e21\u0e34 \u0e44\u0e21\u0e49\u0e40\u0e23\u0e35\u0e22\u0e07 (\u0e17\u0e35\u0e19) <\/strong>\u2013 \u0e17\u0e35\u0e21\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19 \u0e01\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e19\u0e2d\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e43\u0e2b\u0e49\u0e07\u0e32\u0e19\u0e1b\u0e31\u0e07\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/li><li><strong>\u0e40\u0e2a\u0e0f\u0e10\u0e27\u0e38\u0e12\u0e34 \u0e2a\u0e38\u0e02\u0e2a\u0e07 (\u0e40\u0e1b\u0e49\u0e2d) <\/strong>\u2013 \u0e0a\u0e48\u0e32\u0e07\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e17\u0e24\u0e29\u0e0e\u0e35\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e21\u0e38\u0e21\u0e44\u0e2b\u0e19\u0e2a\u0e31\u0e48\u0e07\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/li><li><strong>\u0e16\u0e19\u0e2d\u0e21\u0e1e\u0e07\u0e28\u0e4c \u0e44\u0e0a\u0e22\u0e1e\u0e25\u0e24\u0e17\u0e18\u0e34\u0e4c (\u0e40\u0e25\u0e47\u0e01) <\/strong>\u2013 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e48\u0e32\u0e07\u0e20\u0e32\u0e1e \u0e0b\u0e31\u0e1b\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e43\u0e08\u0e01\u0e31\u0e19<\/li><li><strong>\u0e2a\u0e38\u0e23\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e1a\u0e31\u0e27\u0e41\u0e01\u0e49\u0e27<\/strong><strong> (\u0e04\u0e23\u0e39\u0e15\u0e49\u0e19) <\/strong>\u2013 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e23\u0e35 \u0e42\u0e1e\u0e23 \u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19<\/li><li><strong>\u0e2a\u0e34\u0e23\u0e19\u0e38\u0e0a \u0e1a\u0e38\u0e0d\u0e44\u0e17\u0e22<\/strong><strong> (\u0e04\u0e23\u0e39\u0e01\u0e49\u0e2d\u0e22) <\/strong>\u2013 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04<\/li><li><strong>\u0e08\u0e23\u0e39\u0e0d \u0e04\u0e23\u0e38\u0e11\u0e08\u0e49\u0e2d\u0e19<\/strong><strong> (\u0e04\u0e23\u0e39\u0e2d\u0e2d) <\/strong>\u2013 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04<\/li><li><strong>\u0e27\u0e34\u0e23\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e1e\u0e25\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c <\/strong><strong>(\u0e04\u0e23\u0e39\u0e22\u0e38\u0e49\u0e22) <\/strong>\u2013 \u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e40\u0e27\u0e25\u0e32<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-950cd41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"950cd41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-673f31f\" data-id=\"673f31f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1e1a36 elementor-widget elementor-widget-spacer\" data-id=\"d1e1a36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36cd352c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36cd352c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7d41c303\" data-id=\"7d41c303\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3fc3212a\" data-id=\"3fc3212a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d9c30d9 elementor-widget elementor-widget-image\" data-id=\"6d9c30d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"347\" src=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/BCG_ENTH-01.png\" class=\"attachment-large size-large wp-image-29195\" alt=\"BCG Economy Model\" srcset=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/BCG_ENTH-01.png 700w, https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/BCG_ENTH-01-300x162.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7d764b05\" data-id=\"7d764b05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"author":24,"featured_media":35952,"template":"","categories":[1077,252,253,254],"tags":[1403,2789,2973,2790,2791,2970,2974],"class_list":["post-35943","news_post","type-news_post","status-publish","has-post-thumbnail","hentry","category-bcg-cat","category-news-cat","category-pr-cat","category-article-cat","tag-bcg-economy-model","tag-bcg-happy-story","tag-thunsong-hometown","tag-2790","tag-2791","tag-2970","tag-2974"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49 - NSTDA<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d 3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49 - NSTDA\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d 3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/\" \/>\n<meta property=\"og:site_name\" content=\"NSTDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NSTDATHAILAND\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-08T08:43:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nstdathailand\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/\",\"name\":\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49 - NSTDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/thungsong_17.jpg\",\"datePublished\":\"2022-09-14T07:58:35+00:00\",\"dateModified\":\"2023-03-08T08:43:10+00:00\",\"description\":\"\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d 3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/thungsong_17.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/thungsong_17.jpg\",\"width\":700,\"height\":394,\"caption\":\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/bcg-happy-story-thungsong-hometown\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\",\"item\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/news_post\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"name\":\"NSTDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#organization\",\"name\":\"NSTDA\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"contentUrl\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nstda-202010-h150.png\",\"width\":434,\"height\":150,\"caption\":\"NSTDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nstda.or.th\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NSTDATHAILAND\",\"https:\\\/\\\/x.com\\\/nstdathailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49 - NSTDA","description":"\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d 3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49 - NSTDA","og_description":"\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d 3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23","og_url":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/","og_site_name":"NSTDA","article_publisher":"https:\/\/www.facebook.com\/NSTDATHAILAND","article_modified_time":"2023-03-08T08:43:10+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nstdathailand","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/","url":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/","name":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49 - NSTDA","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg","datePublished":"2022-09-14T07:58:35+00:00","dateModified":"2023-03-08T08:43:10+00:00","description":"\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e02\u0e2d 3 \u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e14\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e25\u0e39\u0e01\u0e2a\u0e31\u0e01\u0e17\u0e35\u0e40\u0e16\u0e34\u0e14!!\u201d \u0e44\u0e2d\u0e0b\u0e4c\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1e\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e0a\u0e49\u0e21\u0e37\u0e2d\u0e16\u0e39\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d B-C-G \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u201c\u0e2b\u0e30 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/#primaryimage","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/09\/thungsong_17.jpg","width":700,"height":394,"caption":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/home\/news_post\/bcg-happy-story-thungsong-hometown\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.nstda.or.th\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27","item":"https:\/\/www.nstda.or.th\/home\/news_post\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e21\u0e35\u0e40\u0e25\u0e02\u0e40\u0e14\u0e47\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07? Thungsong Hometown \u0e21\u0e35 \u2018\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e15\u0e23\u0e07\u2019 \u0e08\u0e30\u0e43\u0e2b\u0e49"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/home\/#website","url":"https:\/\/www.nstda.or.th\/home\/","name":"NSTDA","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/home\/#organization","name":"NSTDA","url":"https:\/\/www.nstda.or.th\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","contentUrl":"https:\/\/www.nstda.or.th\/home\/wp-content\/uploads\/2022\/01\/logo-nstda-202010-h150.png","width":434,"height":150,"caption":"NSTDA"},"image":{"@id":"https:\/\/www.nstda.or.th\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NSTDATHAILAND","https:\/\/x.com\/nstdathailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/35943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post"}],"about":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/types\/news_post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/users\/24"}],"version-history":[{"count":30,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/35943\/revisions"}],"predecessor-version":[{"id":41076,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/news_post\/35943\/revisions\/41076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media\/35952"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/media?parent=35943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/categories?post=35943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/home\/wp-json\/wp\/v2\/tags?post=35943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}