{"id":2312,"date":"2026-06-04T11:09:51","date_gmt":"2026-06-04T04:09:51","guid":{"rendered":"https:\/\/www.nstda.or.th\/foodbank\/?p=2312"},"modified":"2026-06-30T11:23:17","modified_gmt":"2026-06-30T04:23:17","slug":"cp-nstda-sos-4-june-2026","status":"publish","type":"post","link":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/","title":{"rendered":"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u201c\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23\u2013\u0e42\u0e25\u0e15\u0e31\u0e2a\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e33\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.), \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2a\u0e42\u0e01\u0e25\u0e32\u0e23\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e0b\u0e31\u0e2a\u0e17\u0e35\u0e41\u0e19\u0e19\u0e0b\u0e4c (SOS) \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 Thailand Food Bank \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u201c\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-02-768x512-1.jpg\" alt=\"\" class=\"wp-image-2314\" srcset=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-02-768x512-1.jpg 768w, https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-02-768x512-1-300x200.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e01\u0e34\u0e01\u0e23\u0e23\u0e21\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e13 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e23\u0e32\u0e21 \u0e40\u0e02\u0e15\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e32\u0e2a\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e08\u0e01\u0e08\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 150 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 \u0e0b\u0e36\u0e48\u0e07 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e40\u0e02\u0e15\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e01\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1b\u0e35 2569 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d \u0e04\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e01\u0e27\u0e48\u0e32 250 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e1c\u0e2a\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e31\u0e19\u0e1c\u0e48\u0e32\u0e19 Line OA \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e25\u0e14\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e49\u0e33\u0e0b\u0e49\u0e2d\u0e19 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e14\u0e49\u0e32\u0e19 \u201c\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01 \u0e2a\u0e27\u0e17\u0e0a. \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32 test kit \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e31\u0e14\u0e01\u0e23\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e17\u0e32\u0e07 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2a\u0e42\u0e01\u0e25\u0e32\u0e23\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e0b\u0e31\u0e2a\u0e17\u0e35\u0e41\u0e19\u0e19\u0e0b\u0e4c (SOS) \u0e17\u0e35\u0e48\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e48\u0e27\u0e22\u0e04\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-09-768x512-1.jpg\" alt=\"\" class=\"wp-image-2315\" srcset=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-09-768x512-1.jpg 768w, https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-09-768x512-1-300x200.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e32\u0e07\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e23 \u0e40\u0e14\u0e0a\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u201c\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e19\u0e33\u0e25\u0e07\u0e08\u0e32\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e41\u0e25\u0e30\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u2018\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u2019 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e23\u0e32\u0e30\u0e1a\u0e32\u0e07<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-05-600x400-1.jpg\" alt=\"\" class=\"wp-image-2316\" srcset=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-05-600x400-1.jpg 600w, https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-05-600x400-1-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-03-600x400-1.jpg\" alt=\"\" class=\"wp-image-2318\" srcset=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-03-600x400-1.jpg 600w, https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-03-600x400-1-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-04-600x400-1.jpg\" alt=\"\" class=\"wp-image-2319\" srcset=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-04-600x400-1.jpg 600w, https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-04-600x400-1-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-07-600x400-2.jpg\" alt=\"\" class=\"wp-image-2320\" srcset=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-07-600x400-2.jpg 600w, https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-07-600x400-2-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u2018\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u2019 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e32\u0e2a\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01\u0e41\u0e08\u0e01\u0e08\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23 \u201c\u0e25\u0e14\u0e17\u0e34\u0e49\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e48\u0e32\u201d \u0e08\u0e32\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e02\u0e32\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23\u0e41\u0e25\u0e30\u0e42\u0e25\u0e15\u0e31\u0e2a\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e17\u0e35\u0e48\u0e21\u0e32: The CEO Spectrum Business Plus, www.thebusinessplus.com\/cpaxtra-46<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u201c\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23\u2013\u0e42\u0e25\u0e15\u0e31\u0e2a\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e33\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.), \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2a\u0e42\u0e01\u0e25\u0e32\u0e23\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e0b\u0e31\u0e2a\u0e17\u0e35\u0e41\u0e19\u0e19\u0e0b\u0e4c (SOS) \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 Thailand Food Bank \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u201c\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e01\u0e34\u0e01\u0e23\u0e23\u0e21\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e13 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e23\u0e32\u0e21 \u0e40\u0e02\u0e15\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e32\u0e2a\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e08\u0e01\u0e08\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 150 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 \u0e0b\u0e36\u0e48\u0e07 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e40\u0e02\u0e15\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e01\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[16,17,33,18],"class_list":["post-2312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","tag-food-bank","tag-food-surplus","tag-nstda","tag-thailands-food-bank"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d - FoodBank<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d - FoodBank\" \/>\n<meta property=\"og:description\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u201c\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23\u2013\u0e42\u0e25\u0e15\u0e31\u0e2a\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e33\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.), \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2a\u0e42\u0e01\u0e25\u0e32\u0e23\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e0b\u0e31\u0e2a\u0e17\u0e35\u0e41\u0e19\u0e19\u0e0b\u0e4c (SOS) \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 Thailand Food Bank \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u201c\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e01\u0e34\u0e01\u0e23\u0e23\u0e21\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e13 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e23\u0e32\u0e21 \u0e40\u0e02\u0e15\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e32\u0e2a\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e08\u0e01\u0e08\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 150 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 \u0e0b\u0e36\u0e48\u0e07 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e40\u0e02\u0e15\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e01\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"FoodBank\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-04T04:09:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T04:23:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\"},\"author\":{\"name\":\"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/person\/927b6a7b82a12dd075a53e975613c773\"},\"headline\":\"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d\",\"datePublished\":\"2026-06-04T04:09:51+00:00\",\"dateModified\":\"2026-06-30T04:23:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\"},\"wordCount\":21,\"publisher\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg\",\"keywords\":[\"Food Bank\",\"Food surplus\",\"NSTDA\",\"Thailand\u2019s Food Bank\"],\"articleSection\":[\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \/ \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\",\"url\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\",\"name\":\"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d - FoodBank\",\"isPartOf\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg\",\"datePublished\":\"2026-06-04T04:09:51+00:00\",\"dateModified\":\"2026-06-30T04:23:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage\",\"url\":\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg\",\"contentUrl\":\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nstda.or.th\/foodbank\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#website\",\"url\":\"https:\/\/www.nstda.or.th\/foodbank\/\",\"name\":\"FoodBank\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nstda.or.th\/foodbank\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#organization\",\"name\":\"FoodBank\",\"url\":\"https:\/\/www.nstda.or.th\/foodbank\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2025\/08\/FOOD-BANK-LOGO2_1.png\",\"contentUrl\":\"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2025\/08\/FOOD-BANK-LOGO2_1.png\",\"width\":135,\"height\":75,\"caption\":\"FoodBank\"},\"image\":{\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/person\/927b6a7b82a12dd075a53e975613c773\",\"name\":\"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/53214c460ff7d614b28ce506b4726e2253c15d16bf6e00e17a3692bd9f596677?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53214c460ff7d614b28ce506b4726e2253c15d16bf6e00e17a3692bd9f596677?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53214c460ff7d614b28ce506b4726e2253c15d16bf6e00e17a3692bd9f596677?s=96&d=mm&r=g\",\"caption\":\"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d - FoodBank","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/","og_locale":"en_US","og_type":"article","og_title":"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d - FoodBank","og_description":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u201c\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23\u2013\u0e42\u0e25\u0e15\u0e31\u0e2a\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e33\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e19\u0e36\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.), \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2a\u0e42\u0e01\u0e25\u0e32\u0e23\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e0b\u0e31\u0e2a\u0e17\u0e35\u0e41\u0e19\u0e19\u0e0b\u0e4c (SOS) \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 Thailand Food Bank \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u201c\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u201d \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e01\u0e34\u0e01\u0e23\u0e23\u0e21\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07 \u0e13 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e23\u0e32\u0e21 \u0e40\u0e02\u0e15\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e32\u0e2a\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e08\u0e01\u0e08\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 150 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 \u0e0b\u0e36\u0e48\u0e07 \u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e40\u0e02\u0e15\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e01\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 [&hellip;]","og_url":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/","og_site_name":"FoodBank","article_published_time":"2026-06-04T04:09:51+00:00","article_modified_time":"2026-06-30T04:23:17+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg","type":"image\/jpeg"}],"author":"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#article","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/"},"author":{"name":"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33","@id":"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/person\/927b6a7b82a12dd075a53e975613c773"},"headline":"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d","datePublished":"2026-06-04T04:09:51+00:00","dateModified":"2026-06-30T04:23:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/"},"wordCount":21,"publisher":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/#organization"},"image":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg","keywords":["Food Bank","Food surplus","NSTDA","Thailand\u2019s Food Bank"],"articleSection":["\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \/ \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/","url":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/","name":"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d - FoodBank","isPartOf":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg","datePublished":"2026-06-04T04:09:51+00:00","dateModified":"2026-06-30T04:23:17+00:00","breadcrumb":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#primaryimage","url":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg","contentUrl":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2026\/06\/\u0e0b\u0e35\u0e1e\u0e35-\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32-\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19-01.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.nstda.or.th\/foodbank\/cp-nstda-sos-4-june-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nstda.or.th\/foodbank\/"},{"@type":"ListItem","position":2,"name":"\u0e0b\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e1c\u0e19\u0e36\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 SOS \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e01\u0e34\u0e19\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u201d \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49-\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e21\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e27\u0e48\u0e32 5 \u0e25\u0e49\u0e32\u0e19\u0e21\u0e37\u0e49\u0e2d"}]},{"@type":"WebSite","@id":"https:\/\/www.nstda.or.th\/foodbank\/#website","url":"https:\/\/www.nstda.or.th\/foodbank\/","name":"FoodBank","description":"","publisher":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nstda.or.th\/foodbank\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nstda.or.th\/foodbank\/#organization","name":"FoodBank","url":"https:\/\/www.nstda.or.th\/foodbank\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/logo\/image\/","url":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2025\/08\/FOOD-BANK-LOGO2_1.png","contentUrl":"https:\/\/www.nstda.or.th\/foodbank\/wp-content\/uploads\/2025\/08\/FOOD-BANK-LOGO2_1.png","width":135,"height":75,"caption":"FoodBank"},"image":{"@id":"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.nstda.or.th\/foodbank\/#\/schema\/person\/927b6a7b82a12dd075a53e975613c773","name":"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/53214c460ff7d614b28ce506b4726e2253c15d16bf6e00e17a3692bd9f596677?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53214c460ff7d614b28ce506b4726e2253c15d16bf6e00e17a3692bd9f596677?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53214c460ff7d614b28ce506b4726e2253c15d16bf6e00e17a3692bd9f596677?s=96&d=mm&r=g","caption":"\u0e08\u0e35\u0e23\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e14\u0e27\u0e07\u0e04\u0e33"}}]}},"_links":{"self":[{"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/posts\/2312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/comments?post=2312"}],"version-history":[{"count":1,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/posts\/2312\/revisions"}],"predecessor-version":[{"id":2321,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/posts\/2312\/revisions\/2321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/media\/2313"}],"wp:attachment":[{"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/media?parent=2312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/categories?post=2312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nstda.or.th\/foodbank\/wp-json\/wp\/v2\/tags?post=2312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}